{"id":1215,"date":"2021-06-28T09:16:16","date_gmt":"2021-06-28T09:16:16","guid":{"rendered":"https:\/\/www.academica.school\/news\/?p=1215"},"modified":"2021-06-28T09:19:23","modified_gmt":"2021-06-28T09:19:23","slug":"el-diploma-dual-o-como-lograr-la-internacionalizacion-de-tu-colegio","status":"publish","type":"post","link":"https:\/\/www.academica.school\/news\/el-diploma-dual-o-como-lograr-la-internacionalizacion-de-tu-colegio\/","title":{"rendered":"El Diploma Dual o c\u00f3mo lograr la internacionalizaci\u00f3n de tu colegio"},"content":{"rendered":"<p>El Diploma Dual de<strong> Academica International Studies<\/strong> es una oportunidad fant\u00e1stica para lograr la internacionalizaci\u00f3n de los colegios espa\u00f1oles, al ofrecer el curricular estadounidense a aquellos de sus alumnos que lo deseen.<\/p>\n<p><!--more--><\/p>\n<p>De esta forma, cualquier alumno que est\u00e9 estudiando en Espa\u00f1a puede beneficiarse y matricularse de forma simult\u00e1nea en el <em>High School<\/em> americano y conseguir la titulaci\u00f3n al finalizar sus estudios en su pa\u00eds de origen.<\/p>\n<p>Se trata de una oportunidad para avanzar no s\u00f3lo en el dominio de la lengua inglesa, sino tambi\u00e9n es ocasi\u00f3n para profundizar en la cultura estadounidense (ya que algunas de las asignaturas permiten por ejemplo conocer su historia), tratar a otros alumnos internacionales a trav\u00e9s de <em>live sessions<\/em>, a los propios profesores estadounidenses que hacen el seguimiento y eval\u00faan de forma contin\u00faa a los alumnos del Diploma Dual de <strong>Academica<\/strong>.<\/p>\n<p>Y es que hoy en d\u00eda la globalizaci\u00f3n hace necesario que los centros educativos se planteen su labor en un marco mucho m\u00e1s amplio y requiere que forman en nuevas competencias a sus alumnos. La sociedad lo reclama y las familias lo esperan.<\/p>\n<p><strong> Ofrecer el Diploma Dual en tu centro escolar permitir\u00e1 beneficiarte, entre otras, de las siguientes ventajas:<\/strong><\/p>\n<ul>\n<li>Ampliar\u00e1s la oferta educativa de tu colegio\/instituto.<\/li>\n<li>Conseguir\u00e1s una clara diferenciaci\u00f3n con respecto a otros centros dentro de tu \u00e1mbito de influencia.<\/li>\n<li>Ofrecer\u00e1s a las familias una oportunidad \u00fanica para que sus hijos dominen el ingl\u00e9s.<\/li>\n<li>Dar\u00e1s la llave de la cultura estadounidense a tus alumnos, abri\u00e9ndoles la posibilidad de estudiar y trabajar en un futuro en este pa\u00eds<\/li>\n<li>Estar\u00e1s dotando a tus alumnos de una experiencia de internacionalizaci\u00f3n sin sacarlos de su entorno natural.<\/li>\n<li>Ofrecer\u00e1s una nueva actividad extraescolar sin recursos adicionales.<\/li>\n<\/ul>\n<p>El Diploma Dual es el programa oficial de convalidaci\u00f3n internacional de t\u00edtulos de bachillerato creado y desarrollado por <strong>Academica Corp.<\/strong> Est\u00e1 presente en Espa\u00f1a desde 2009. Actualmente, cerca de 700 centros en nuestro pa\u00eds ofrecen esta doble titulaci\u00f3n estadounidense, formando parte de nuestra red de centros adheridos. Adem\u00e1s, el Diploma Dual est\u00e1 presente en m\u00e1s de 15 pa\u00edses de los cinco continentes, y son miles los alumnos que ya se han beneficiado de su triple inversi\u00f3n: personal, tecnol\u00f3gica y ling\u00fc\u00edstica.<\/p>\n<p>Si deseas m\u00e1s informaci\u00f3n para tu centro escolar, convertirte en un centro adherido al Diploma Dual o si deseas que tus hijos obtengan el <em>American High School Diploma<\/em> de <strong>Academica<\/strong> a partir del curso que viene, puedes ver el siguiente v\u00eddeo que hemos preparado, en el que te contamos en qu\u00e9 consiste nuestra propuesta educativa. Tambi\u00e9n puedes escribirnos a info@academica.school. Academica, preparando estudiantes para los nuevos retos.<\/p>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"1170\" height=\"659\" src=\"https:\/\/www.youtube.com\/embed\/WaHfn4OT4sM?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=es-ES&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Diploma Dual de Academica International Studies es una oportunidad fant\u00e1stica para lograr la internacionalizaci\u00f3n de los colegios espa\u00f1oles, al ofrecer el curricular estadounidense a aquellos de sus alumnos que lo deseen.<\/p>\n","protected":false},"author":1,"featured_media":1217,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[9,198,118,7,283,4,29,145,285,287,262,286,75,284,30],"class_list":["post-1215","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-last-news","tag-academica","tag-american-high-school","tag-centros-escolares","tag-colegios","tag-diploma","tag-diploma-dual","tag-ee-uu","tag-eeuu","tag-estadounidense","tag-estudios","tag-institutos","tag-norteamericana","tag-secundaria","tag-titulacion","tag-usa","clearfix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Diploma Dual o c\u00f3mo lograr la internacionalizaci\u00f3n de tu colegio - Academica News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.academica.school\/news\/el-diploma-dual-o-como-lograr-la-internacionalizacion-de-tu-colegio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Diploma Dual o c\u00f3mo lograr la internacionalizaci\u00f3n de tu colegio - Academica News\" \/>\n<meta property=\"og:description\" content=\"El Diploma Dual de Academica International Studies es una oportunidad fant\u00e1stica para lograr la internacionalizaci\u00f3n de los colegios espa\u00f1oles, al ofrecer el curricular estadounidense a aquellos de sus alumnos que lo deseen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.academica.school\/news\/el-diploma-dual-o-como-lograr-la-internacionalizacion-de-tu-colegio\/\" \/>\n<meta property=\"og:site_name\" content=\"Academica News\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-28T09:16:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-28T09:19:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2021\/06\/116141123_mediaitem116141122.jpg?fit=801%2C500&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"801\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Academica Spain\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Academica Spain\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/el-diploma-dual-o-como-lograr-la-internacionalizacion-de-tu-colegio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/el-diploma-dual-o-como-lograr-la-internacionalizacion-de-tu-colegio\\\/\"},\"author\":{\"name\":\"Academica Spain\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#\\\/schema\\\/person\\\/07ed699df26b3ae2c049959a107fce05\"},\"headline\":\"El Diploma Dual o c\u00f3mo lograr la internacionalizaci\u00f3n de tu colegio\",\"datePublished\":\"2021-06-28T09:16:16+00:00\",\"dateModified\":\"2021-06-28T09:19:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/el-diploma-dual-o-como-lograr-la-internacionalizacion-de-tu-colegio\\\/\"},\"wordCount\":494,\"publisher\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/el-diploma-dual-o-como-lograr-la-internacionalizacion-de-tu-colegio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/116141123_mediaitem116141122.jpg?fit=801%2C500&ssl=1\",\"keywords\":[\"academica\",\"american high school\",\"centros escolares\",\"colegios\",\"diploma\",\"Diploma Dual\",\"ee.uu.\",\"eeuu\",\"estadounidense\",\"estudios\",\"institutos\",\"norteamericana\",\"secundaria\",\"titulacion\",\"usa\"],\"articleSection\":[\"Last News\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/el-diploma-dual-o-como-lograr-la-internacionalizacion-de-tu-colegio\\\/\",\"url\":\"https:\\\/\\\/www.academica.school\\\/news\\\/el-diploma-dual-o-como-lograr-la-internacionalizacion-de-tu-colegio\\\/\",\"name\":\"El Diploma Dual o c\u00f3mo lograr la internacionalizaci\u00f3n de tu colegio - Academica News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/el-diploma-dual-o-como-lograr-la-internacionalizacion-de-tu-colegio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/el-diploma-dual-o-como-lograr-la-internacionalizacion-de-tu-colegio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/116141123_mediaitem116141122.jpg?fit=801%2C500&ssl=1\",\"datePublished\":\"2021-06-28T09:16:16+00:00\",\"dateModified\":\"2021-06-28T09:19:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/el-diploma-dual-o-como-lograr-la-internacionalizacion-de-tu-colegio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.academica.school\\\/news\\\/el-diploma-dual-o-como-lograr-la-internacionalizacion-de-tu-colegio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/el-diploma-dual-o-como-lograr-la-internacionalizacion-de-tu-colegio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/116141123_mediaitem116141122.jpg?fit=801%2C500&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/116141123_mediaitem116141122.jpg?fit=801%2C500&ssl=1\",\"width\":801,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/el-diploma-dual-o-como-lograr-la-internacionalizacion-de-tu-colegio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.academica.school\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Diploma Dual o c\u00f3mo lograr la internacionalizaci\u00f3n de tu colegio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/www.academica.school\\\/news\\\/\",\"name\":\"Academica News\",\"description\":\"todo lo que pasa en el mundo acad\u00e9mico, sobre universidades y cualquier evento o novedad en la que participemos\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.academica.school\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#organization\",\"name\":\"Academica\",\"url\":\"https:\\\/\\\/www.academica.school\\\/news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Captura-de-pantalla-2019-11-20-a-las-12.14.04.png?fit=799%2C500&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Captura-de-pantalla-2019-11-20-a-las-12.14.04.png?fit=799%2C500&ssl=1\",\"width\":799,\"height\":500,\"caption\":\"Academica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#\\\/schema\\\/person\\\/07ed699df26b3ae2c049959a107fce05\",\"name\":\"Academica Spain\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/24d850e4f123aaa0ad5edf9a3fb1d97a98b831f0571142c5dc4b3add4e2db2ea?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/24d850e4f123aaa0ad5edf9a3fb1d97a98b831f0571142c5dc4b3add4e2db2ea?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/24d850e4f123aaa0ad5edf9a3fb1d97a98b831f0571142c5dc4b3add4e2db2ea?s=96&d=mm&r=g\",\"caption\":\"Academica Spain\"},\"url\":\"https:\\\/\\\/www.academica.school\\\/news\\\/author\\\/jasubal\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Diploma Dual o c\u00f3mo lograr la internacionalizaci\u00f3n de tu colegio - Academica News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.academica.school\/news\/el-diploma-dual-o-como-lograr-la-internacionalizacion-de-tu-colegio\/","og_locale":"es_ES","og_type":"article","og_title":"El Diploma Dual o c\u00f3mo lograr la internacionalizaci\u00f3n de tu colegio - Academica News","og_description":"El Diploma Dual de Academica International Studies es una oportunidad fant\u00e1stica para lograr la internacionalizaci\u00f3n de los colegios espa\u00f1oles, al ofrecer el curricular estadounidense a aquellos de sus alumnos que lo deseen.","og_url":"https:\/\/www.academica.school\/news\/el-diploma-dual-o-como-lograr-la-internacionalizacion-de-tu-colegio\/","og_site_name":"Academica News","article_published_time":"2021-06-28T09:16:16+00:00","article_modified_time":"2021-06-28T09:19:23+00:00","og_image":[{"width":801,"height":500,"url":"https:\/\/i1.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2021\/06\/116141123_mediaitem116141122.jpg?fit=801%2C500&ssl=1","type":"image\/jpeg"}],"author":"Academica Spain","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Academica Spain","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.academica.school\/news\/el-diploma-dual-o-como-lograr-la-internacionalizacion-de-tu-colegio\/#article","isPartOf":{"@id":"https:\/\/www.academica.school\/news\/el-diploma-dual-o-como-lograr-la-internacionalizacion-de-tu-colegio\/"},"author":{"name":"Academica Spain","@id":"https:\/\/www.academica.school\/news\/#\/schema\/person\/07ed699df26b3ae2c049959a107fce05"},"headline":"El Diploma Dual o c\u00f3mo lograr la internacionalizaci\u00f3n de tu colegio","datePublished":"2021-06-28T09:16:16+00:00","dateModified":"2021-06-28T09:19:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.academica.school\/news\/el-diploma-dual-o-como-lograr-la-internacionalizacion-de-tu-colegio\/"},"wordCount":494,"publisher":{"@id":"https:\/\/www.academica.school\/news\/#organization"},"image":{"@id":"https:\/\/www.academica.school\/news\/el-diploma-dual-o-como-lograr-la-internacionalizacion-de-tu-colegio\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2021\/06\/116141123_mediaitem116141122.jpg?fit=801%2C500&ssl=1","keywords":["academica","american high school","centros escolares","colegios","diploma","Diploma Dual","ee.uu.","eeuu","estadounidense","estudios","institutos","norteamericana","secundaria","titulacion","usa"],"articleSection":["Last News"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.academica.school\/news\/el-diploma-dual-o-como-lograr-la-internacionalizacion-de-tu-colegio\/","url":"https:\/\/www.academica.school\/news\/el-diploma-dual-o-como-lograr-la-internacionalizacion-de-tu-colegio\/","name":"El Diploma Dual o c\u00f3mo lograr la internacionalizaci\u00f3n de tu colegio - Academica News","isPartOf":{"@id":"https:\/\/www.academica.school\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.academica.school\/news\/el-diploma-dual-o-como-lograr-la-internacionalizacion-de-tu-colegio\/#primaryimage"},"image":{"@id":"https:\/\/www.academica.school\/news\/el-diploma-dual-o-como-lograr-la-internacionalizacion-de-tu-colegio\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2021\/06\/116141123_mediaitem116141122.jpg?fit=801%2C500&ssl=1","datePublished":"2021-06-28T09:16:16+00:00","dateModified":"2021-06-28T09:19:23+00:00","breadcrumb":{"@id":"https:\/\/www.academica.school\/news\/el-diploma-dual-o-como-lograr-la-internacionalizacion-de-tu-colegio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.academica.school\/news\/el-diploma-dual-o-como-lograr-la-internacionalizacion-de-tu-colegio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.academica.school\/news\/el-diploma-dual-o-como-lograr-la-internacionalizacion-de-tu-colegio\/#primaryimage","url":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2021\/06\/116141123_mediaitem116141122.jpg?fit=801%2C500&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2021\/06\/116141123_mediaitem116141122.jpg?fit=801%2C500&ssl=1","width":801,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.academica.school\/news\/el-diploma-dual-o-como-lograr-la-internacionalizacion-de-tu-colegio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.academica.school\/news\/"},{"@type":"ListItem","position":2,"name":"El Diploma Dual o c\u00f3mo lograr la internacionalizaci\u00f3n de tu colegio"}]},{"@type":"WebSite","@id":"https:\/\/www.academica.school\/news\/#website","url":"https:\/\/www.academica.school\/news\/","name":"Academica News","description":"todo lo que pasa en el mundo acad\u00e9mico, sobre universidades y cualquier evento o novedad en la que participemos","publisher":{"@id":"https:\/\/www.academica.school\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.academica.school\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.academica.school\/news\/#organization","name":"Academica","url":"https:\/\/www.academica.school\/news\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.academica.school\/news\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2019\/11\/Captura-de-pantalla-2019-11-20-a-las-12.14.04.png?fit=799%2C500&ssl=1","contentUrl":"https:\/\/i1.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2019\/11\/Captura-de-pantalla-2019-11-20-a-las-12.14.04.png?fit=799%2C500&ssl=1","width":799,"height":500,"caption":"Academica"},"image":{"@id":"https:\/\/www.academica.school\/news\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.academica.school\/news\/#\/schema\/person\/07ed699df26b3ae2c049959a107fce05","name":"Academica Spain","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/24d850e4f123aaa0ad5edf9a3fb1d97a98b831f0571142c5dc4b3add4e2db2ea?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/24d850e4f123aaa0ad5edf9a3fb1d97a98b831f0571142c5dc4b3add4e2db2ea?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/24d850e4f123aaa0ad5edf9a3fb1d97a98b831f0571142c5dc4b3add4e2db2ea?s=96&d=mm&r=g","caption":"Academica Spain"},"url":"https:\/\/www.academica.school\/news\/author\/jasubal\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2021\/06\/116141123_mediaitem116141122.jpg?fit=801%2C500&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8RDKh-jB","jetpack-related-posts":[{"id":2416,"url":"https:\/\/www.academica.school\/news\/el-diploma-dual-me-ha-ensenado-a-organizar-mejor-mis-estudios\/","url_meta":{"origin":1215,"position":0},"title":"\u00abEl Diploma Dual me ha ense\u00f1ado a organizar mejor mis estudios\u00bb","author":"Academica Spain","date":"mayo 8, 2024","format":false,"excerpt":"Vera est\u00e1 cursando 3\u00ba de la ESO en el Colegio Santa Teresa de Jes\u00fas de Salamanca y est\u00e1 haciendo al mismo tiempo el Diploma Dual. Est\u00e1n siendo unos a\u00f1os de gran aprendizaje para ella, en los que no s\u00f3lo est\u00e1 mejorando sus destrezas en el ingl\u00e9s, sino que le est\u00e1\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"colegio-santa-teresa-de-jesus-salamanca-diploma-dual-academica","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2024\/05\/Testimonio-Vera-scaled-e1715160467406.jpg?fit=530%2C648&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2024\/05\/Testimonio-Vera-scaled-e1715160467406.jpg?fit=530%2C648&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2024\/05\/Testimonio-Vera-scaled-e1715160467406.jpg?fit=530%2C648&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":582,"url":"https:\/\/www.academica.school\/news\/los-alumnos-de-2oeso-pueden-comenzar-a-cursar-el-diploma-dual\/","url_meta":{"origin":1215,"position":1},"title":"Los alumnos de 2\u00baESO pueden comenzar a cursar el Diploma Dual","author":"Academica Spain","date":"marzo 27, 2019","format":false,"excerpt":"Academica Spain ha anunciado que, aquellos alumnos de 2\u00baESO que lo deseen, podr\u00e1n comenzar sus estudios del Diploma Dual, tal y como ya se empezara a hacer el curso pasado, y obtener as\u00ed la doble titulaci\u00f3n de High School americano al mismo tiempo que obtienen su t\u00edtulo de ESO y\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2019\/03\/img-graduados_academica-graduados-2018-3563-1.jpg?fit=800%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2019\/03\/img-graduados_academica-graduados-2018-3563-1.jpg?fit=800%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2019\/03\/img-graduados_academica-graduados-2018-3563-1.jpg?fit=800%2C500&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2019\/03\/img-graduados_academica-graduados-2018-3563-1.jpg?fit=800%2C500&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":734,"url":"https:\/\/www.academica.school\/news\/academica-lider-en-educacion-virtual\/","url_meta":{"origin":1215,"position":2},"title":"Academica, l\u00edder en educaci\u00f3n virtual","author":"Academica Spain","date":"junio 19, 2019","format":false,"excerpt":"Con ma\u0301s de 100.000 alumnos, 4.000 profesores y 180 colegios en ma\u0301s de 10 estados, Academica es la principal y mayor institucio\u0301n estadounidense de gestio\u0301n educativa con sede en Miami (Florida) de Charter Schools (colegios pu\u0301blicos de gestio\u0301n 100% privada de alto rendimiento educativo). Academica es una de las pocas\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2019\/06\/Academica-3.jpg?fit=801%2C502&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2019\/06\/Academica-3.jpg?fit=801%2C502&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2019\/06\/Academica-3.jpg?fit=801%2C502&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2019\/06\/Academica-3.jpg?fit=801%2C502&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":694,"url":"https:\/\/www.academica.school\/news\/abierto-el-plazo-de-inscripcion-para-nuevos-alumnos-del-diploma-dual-en-espana\/","url_meta":{"origin":1215,"position":3},"title":"Abierto el plazo de inscripci\u00f3n para nuevos alumnos del Diploma Dual en Espa\u00f1a","author":"Academica Spain","date":"junio 7, 2019","format":false,"excerpt":"Academica Spain abri\u00f3 el pasado mes de abril la web de matriculaciones para nuevos alumnos que deseen cursar el Diploma Dual en Espa\u00f1a a partir del pr\u00f3ximo curso acad\u00e9mico (2019-20). Para ello se ha habilitado la web https:\/\/www.academicaschools.es\/inscripcion\/. El Diploma Dual, programa de doble titulaci\u00f3n de bachillerato estadounidense creado y\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2019\/06\/Inscripciones.jpg?fit=800%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2019\/06\/Inscripciones.jpg?fit=800%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2019\/06\/Inscripciones.jpg?fit=800%2C500&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2019\/06\/Inscripciones.jpg?fit=800%2C500&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":541,"url":"https:\/\/www.academica.school\/news\/el-diario-el-mundo-publica-un-especial-sobre-los-100-mejores-colegios\/","url_meta":{"origin":1215,"position":4},"title":"El diario El Mundo publica un especial sobre los 100 mejores colegios","author":"Academica Spain","date":"marzo 6, 2019","format":false,"excerpt":"El diario El Mundo ha publicado su especial anual \"100 Colegios\" en el que establece el ranking, que a juicio de los expertos que colaboran con el diario, componen este ranking y entre los que figuran muchos colegios adheridos al Diploma Dual en todo el territorio nacional. Por esta raz\u00f3n,\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2019\/03\/ElMundo_2019.jpg?fit=799%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2019\/03\/ElMundo_2019.jpg?fit=799%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2019\/03\/ElMundo_2019.jpg?fit=799%2C500&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2019\/03\/ElMundo_2019.jpg?fit=799%2C500&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":437,"url":"https:\/\/www.academica.school\/news\/los-mejores-colegios-con-doble-titulacion-en-espana\/","url_meta":{"origin":1215,"position":5},"title":"Los mejores colegios con doble titulaci\u00f3n en Espa\u00f1a","author":"Academica Spain","date":"marzo 9, 2018","format":false,"excerpt":"Si hay algo de lo que estamos profundamente orgullosos en Academica Spain es de los colegios que, desde hace a\u00f1os, conf\u00edan en el Diploma Dual. Y, especialmente, de los colegios espa\u00f1oles que se han sumado al programa oficial de convalidaci\u00f3n internacional de t\u00edtulos de bachillerato. Y es que todos estos\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2018\/03\/worldcup0112abc-1.jpg?fit=800%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2018\/03\/worldcup0112abc-1.jpg?fit=800%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2018\/03\/worldcup0112abc-1.jpg?fit=800%2C500&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2018\/03\/worldcup0112abc-1.jpg?fit=800%2C500&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/posts\/1215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/comments?post=1215"}],"version-history":[{"count":1,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/posts\/1215\/revisions"}],"predecessor-version":[{"id":1216,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/posts\/1215\/revisions\/1216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/media\/1217"}],"wp:attachment":[{"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/media?parent=1215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/categories?post=1215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/tags?post=1215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}