{"id":2927,"date":"2025-02-12T09:24:12","date_gmt":"2025-02-12T09:24:12","guid":{"rendered":"https:\/\/www.academica.school\/news\/?p=2927"},"modified":"2025-02-12T09:24:12","modified_gmt":"2025-02-12T09:24:12","slug":"el-diploma-dual-en-el-colegio-santa-teresa-de-jesus-de-salamanca","status":"publish","type":"post","link":"https:\/\/www.academica.school\/news\/el-diploma-dual-en-el-colegio-santa-teresa-de-jesus-de-salamanca\/","title":{"rendered":"El Diploma Dual en el Colegio Santa Teresa de Jes\u00fas de Salamanca"},"content":{"rendered":"<div class=\"\">\n<p>Luc\u00eda y Vega, alumnas del Colegio Santa Teresa de Jes\u00fas de Salamanca, nos cuentan su experiencia cursando el Diploma Dual.<\/p>\n<p><!--more--><\/p>\n<\/div>\n<div class=\"\">\n<div class=\"\">\n<div class=\"\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-text-editor elementor-clearfix\">\n<p>Ambas han finalizado el primer semestre del curso con \u00e9xito, obteniendo buenos resultados. El programa no s\u00f3lo les est\u00e1 ayudando a mejorar sus habilidades de gesti\u00f3n y manejo del tiempo, tambi\u00e9n est\u00e1n mejorando mucho en ingl\u00e9s y est\u00e1n aprendiendo sobre cultura americana.<\/p>\n<\/div>\n<p>El Diploma Dual es el programa oficial de convalidaci\u00f3n internacional de t\u00edtulos de Bachillerato creado y desarrollado por Academica, que permite a los alumnos obtener dos titulaciones simult\u00e1neas: la propia de su pa\u00eds y el American High School Diploma.<\/p>\n<p>Los alumnos del Diploma Dual solamente tienen que cursar 6 asignaturas para obtener la titulaci\u00f3n americana. Los convenios internacionales alcanzados por Academica y la excelencia educativa del programa permiten obtener la m\u00e1xima convalidaci\u00f3n posible: 75% de los 24 cr\u00e9ditos necesarios para obtener el American High School Diploma.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Luc\u00eda y Vega, alumnas del Colegio Santa Teresa de Jes\u00fas de Salamanca, nos cuentan su experiencia cursando el Diploma Dual.<\/p>\n","protected":false},"author":1,"featured_media":2929,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[9,139,89,198,63,208,632,4,222,431],"class_list":["post-2927","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-last-news","tag-academica","tag-academica-spain","tag-alumnos","tag-american-high-school","tag-bachillerato-americano","tag-colegio","tag-colegio-santa-teresa-de-jesus","tag-diploma-dual","tag-dual-diploma","tag-los-300-mejores","post_format-post-format-video","clearfix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Diploma Dual en el Colegio Santa Teresa de Jes\u00fas de Salamanca - Academica News<\/title>\n<meta name=\"description\" content=\"Luc\u00eda y Vega, alumnas del Colegio Santa Teresa de Jes\u00fas de Salamanca, nos cuentan su experiencia cursando el Diploma Dual.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.academica.school\/news\/el-diploma-dual-en-el-colegio-santa-teresa-de-jesus-de-salamanca\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Diploma Dual en el Colegio Santa Teresa de Jes\u00fas de Salamanca - Academica News\" \/>\n<meta property=\"og:description\" content=\"Luc\u00eda y Vega, alumnas del Colegio Santa Teresa de Jes\u00fas de Salamanca, nos cuentan su experiencia cursando el Diploma Dual.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.academica.school\/news\/el-diploma-dual-en-el-colegio-santa-teresa-de-jesus-de-salamanca\/\" \/>\n<meta property=\"og:site_name\" content=\"Academica News\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-12T09:24:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.academica.school\/news\/wp-content\/uploads\/2025\/02\/diploma-dual-academica.png\" \/>\n\t<meta property=\"og:image:width\" content=\"766\" \/>\n\t<meta property=\"og:image:height\" content=\"1374\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Academica Spain\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Academica Spain\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/el-diploma-dual-en-el-colegio-santa-teresa-de-jesus-de-salamanca\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/el-diploma-dual-en-el-colegio-santa-teresa-de-jesus-de-salamanca\\\/\"},\"author\":{\"name\":\"Academica Spain\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#\\\/schema\\\/person\\\/07ed699df26b3ae2c049959a107fce05\"},\"headline\":\"El Diploma Dual en el Colegio Santa Teresa de Jes\u00fas de Salamanca\",\"datePublished\":\"2025-02-12T09:24:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/el-diploma-dual-en-el-colegio-santa-teresa-de-jesus-de-salamanca\\\/\"},\"wordCount\":174,\"publisher\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/el-diploma-dual-en-el-colegio-santa-teresa-de-jesus-de-salamanca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/diploma-dual-academica.png?fit=766%2C1374&ssl=1\",\"keywords\":[\"academica\",\"academica spain\",\"alumnos\",\"american high school\",\"bachillerato americano\",\"colegio\",\"colegio santa teresa de jes\u00fas\",\"Diploma Dual\",\"dual diploma\",\"los 300 mejores\"],\"articleSection\":[\"Last News\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/el-diploma-dual-en-el-colegio-santa-teresa-de-jesus-de-salamanca\\\/\",\"url\":\"https:\\\/\\\/www.academica.school\\\/news\\\/el-diploma-dual-en-el-colegio-santa-teresa-de-jesus-de-salamanca\\\/\",\"name\":\"El Diploma Dual en el Colegio Santa Teresa de Jes\u00fas de Salamanca - Academica News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/el-diploma-dual-en-el-colegio-santa-teresa-de-jesus-de-salamanca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/el-diploma-dual-en-el-colegio-santa-teresa-de-jesus-de-salamanca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/diploma-dual-academica.png?fit=766%2C1374&ssl=1\",\"datePublished\":\"2025-02-12T09:24:12+00:00\",\"description\":\"Luc\u00eda y Vega, alumnas del Colegio Santa Teresa de Jes\u00fas de Salamanca, nos cuentan su experiencia cursando el Diploma Dual.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/el-diploma-dual-en-el-colegio-santa-teresa-de-jesus-de-salamanca\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.academica.school\\\/news\\\/el-diploma-dual-en-el-colegio-santa-teresa-de-jesus-de-salamanca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/el-diploma-dual-en-el-colegio-santa-teresa-de-jesus-de-salamanca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/diploma-dual-academica.png?fit=766%2C1374&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/diploma-dual-academica.png?fit=766%2C1374&ssl=1\",\"width\":766,\"height\":1374,\"caption\":\"diploma-dual-academica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/el-diploma-dual-en-el-colegio-santa-teresa-de-jesus-de-salamanca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.academica.school\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Diploma Dual en el Colegio Santa Teresa de Jes\u00fas de Salamanca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/www.academica.school\\\/news\\\/\",\"name\":\"Academica News\",\"description\":\"todo lo que pasa en el mundo acad\u00e9mico, sobre universidades y cualquier evento o novedad en la que participemos\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.academica.school\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#organization\",\"name\":\"Academica\",\"url\":\"https:\\\/\\\/www.academica.school\\\/news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Captura-de-pantalla-2019-11-20-a-las-12.14.04.png?fit=799%2C500&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Captura-de-pantalla-2019-11-20-a-las-12.14.04.png?fit=799%2C500&ssl=1\",\"width\":799,\"height\":500,\"caption\":\"Academica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#\\\/schema\\\/person\\\/07ed699df26b3ae2c049959a107fce05\",\"name\":\"Academica Spain\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/24d850e4f123aaa0ad5edf9a3fb1d97a98b831f0571142c5dc4b3add4e2db2ea?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/24d850e4f123aaa0ad5edf9a3fb1d97a98b831f0571142c5dc4b3add4e2db2ea?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/24d850e4f123aaa0ad5edf9a3fb1d97a98b831f0571142c5dc4b3add4e2db2ea?s=96&d=mm&r=g\",\"caption\":\"Academica Spain\"},\"url\":\"https:\\\/\\\/www.academica.school\\\/news\\\/author\\\/jasubal\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Diploma Dual en el Colegio Santa Teresa de Jes\u00fas de Salamanca - Academica News","description":"Luc\u00eda y Vega, alumnas del Colegio Santa Teresa de Jes\u00fas de Salamanca, nos cuentan su experiencia cursando el Diploma Dual.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.academica.school\/news\/el-diploma-dual-en-el-colegio-santa-teresa-de-jesus-de-salamanca\/","og_locale":"es_ES","og_type":"article","og_title":"El Diploma Dual en el Colegio Santa Teresa de Jes\u00fas de Salamanca - Academica News","og_description":"Luc\u00eda y Vega, alumnas del Colegio Santa Teresa de Jes\u00fas de Salamanca, nos cuentan su experiencia cursando el Diploma Dual.","og_url":"https:\/\/www.academica.school\/news\/el-diploma-dual-en-el-colegio-santa-teresa-de-jesus-de-salamanca\/","og_site_name":"Academica News","article_published_time":"2025-02-12T09:24:12+00:00","og_image":[{"width":766,"height":1374,"url":"https:\/\/www.academica.school\/news\/wp-content\/uploads\/2025\/02\/diploma-dual-academica.png","type":"image\/png"}],"author":"Academica Spain","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Academica Spain","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.academica.school\/news\/el-diploma-dual-en-el-colegio-santa-teresa-de-jesus-de-salamanca\/#article","isPartOf":{"@id":"https:\/\/www.academica.school\/news\/el-diploma-dual-en-el-colegio-santa-teresa-de-jesus-de-salamanca\/"},"author":{"name":"Academica Spain","@id":"https:\/\/www.academica.school\/news\/#\/schema\/person\/07ed699df26b3ae2c049959a107fce05"},"headline":"El Diploma Dual en el Colegio Santa Teresa de Jes\u00fas de Salamanca","datePublished":"2025-02-12T09:24:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.academica.school\/news\/el-diploma-dual-en-el-colegio-santa-teresa-de-jesus-de-salamanca\/"},"wordCount":174,"publisher":{"@id":"https:\/\/www.academica.school\/news\/#organization"},"image":{"@id":"https:\/\/www.academica.school\/news\/el-diploma-dual-en-el-colegio-santa-teresa-de-jesus-de-salamanca\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/02\/diploma-dual-academica.png?fit=766%2C1374&ssl=1","keywords":["academica","academica spain","alumnos","american high school","bachillerato americano","colegio","colegio santa teresa de jes\u00fas","Diploma Dual","dual diploma","los 300 mejores"],"articleSection":["Last News"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.academica.school\/news\/el-diploma-dual-en-el-colegio-santa-teresa-de-jesus-de-salamanca\/","url":"https:\/\/www.academica.school\/news\/el-diploma-dual-en-el-colegio-santa-teresa-de-jesus-de-salamanca\/","name":"El Diploma Dual en el Colegio Santa Teresa de Jes\u00fas de Salamanca - Academica News","isPartOf":{"@id":"https:\/\/www.academica.school\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.academica.school\/news\/el-diploma-dual-en-el-colegio-santa-teresa-de-jesus-de-salamanca\/#primaryimage"},"image":{"@id":"https:\/\/www.academica.school\/news\/el-diploma-dual-en-el-colegio-santa-teresa-de-jesus-de-salamanca\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/02\/diploma-dual-academica.png?fit=766%2C1374&ssl=1","datePublished":"2025-02-12T09:24:12+00:00","description":"Luc\u00eda y Vega, alumnas del Colegio Santa Teresa de Jes\u00fas de Salamanca, nos cuentan su experiencia cursando el Diploma Dual.","breadcrumb":{"@id":"https:\/\/www.academica.school\/news\/el-diploma-dual-en-el-colegio-santa-teresa-de-jesus-de-salamanca\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.academica.school\/news\/el-diploma-dual-en-el-colegio-santa-teresa-de-jesus-de-salamanca\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.academica.school\/news\/el-diploma-dual-en-el-colegio-santa-teresa-de-jesus-de-salamanca\/#primaryimage","url":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/02\/diploma-dual-academica.png?fit=766%2C1374&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/02\/diploma-dual-academica.png?fit=766%2C1374&ssl=1","width":766,"height":1374,"caption":"diploma-dual-academica"},{"@type":"BreadcrumbList","@id":"https:\/\/www.academica.school\/news\/el-diploma-dual-en-el-colegio-santa-teresa-de-jesus-de-salamanca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.academica.school\/news\/"},{"@type":"ListItem","position":2,"name":"El Diploma Dual en el Colegio Santa Teresa de Jes\u00fas de Salamanca"}]},{"@type":"WebSite","@id":"https:\/\/www.academica.school\/news\/#website","url":"https:\/\/www.academica.school\/news\/","name":"Academica News","description":"todo lo que pasa en el mundo acad\u00e9mico, sobre universidades y cualquier evento o novedad en la que participemos","publisher":{"@id":"https:\/\/www.academica.school\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.academica.school\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.academica.school\/news\/#organization","name":"Academica","url":"https:\/\/www.academica.school\/news\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.academica.school\/news\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2019\/11\/Captura-de-pantalla-2019-11-20-a-las-12.14.04.png?fit=799%2C500&ssl=1","contentUrl":"https:\/\/i1.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2019\/11\/Captura-de-pantalla-2019-11-20-a-las-12.14.04.png?fit=799%2C500&ssl=1","width":799,"height":500,"caption":"Academica"},"image":{"@id":"https:\/\/www.academica.school\/news\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.academica.school\/news\/#\/schema\/person\/07ed699df26b3ae2c049959a107fce05","name":"Academica Spain","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/24d850e4f123aaa0ad5edf9a3fb1d97a98b831f0571142c5dc4b3add4e2db2ea?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/24d850e4f123aaa0ad5edf9a3fb1d97a98b831f0571142c5dc4b3add4e2db2ea?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/24d850e4f123aaa0ad5edf9a3fb1d97a98b831f0571142c5dc4b3add4e2db2ea?s=96&d=mm&r=g","caption":"Academica Spain"},"url":"https:\/\/www.academica.school\/news\/author\/jasubal\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/02\/diploma-dual-academica.png?fit=766%2C1374&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8RDKh-Ld","jetpack-related-posts":[{"id":3186,"url":"https:\/\/www.academica.school\/news\/alumnos-presentan-diploma-dual-teresianas-salamanca\/","url_meta":{"origin":2927,"position":0},"title":"Alumnos del Diploma Dual presentan el programa en el Colegio Santa Teresa de Jes\u00fas de Salamanca","author":"Academica Spain","date":"abril 30, 2025","format":false,"excerpt":"El Colegio Santa Teresa de Jes\u00fas de Salamanca ha realizado la presentaci\u00f3n del Diploma Dual a los alumnos del centro. El colegio ofrece a sus alumnos la posibilidad de obtener dos titulaciones de forma simult\u00e1nea: la propia de su pa\u00eds y el American High School Diploma. En esta ocasi\u00f3n, la\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"diploma-dual-teresianas-salamanca","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/04\/diploma-dual-teresianas-salamanca-2-2.jpg?fit=999%2C740&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/04\/diploma-dual-teresianas-salamanca-2-2.jpg?fit=999%2C740&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/04\/diploma-dual-teresianas-salamanca-2-2.jpg?fit=999%2C740&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/04\/diploma-dual-teresianas-salamanca-2-2.jpg?fit=999%2C740&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":4103,"url":"https:\/\/www.academica.school\/news\/diploma-dual-colegio-santa-teresa-de-jesus-el-vedat-torrent\/","url_meta":{"origin":2927,"position":1},"title":"El Diploma Dual en el Colegio Santa Teresa de Jes\u00fas El Vedat de Torrent","author":"Academica Spain","date":"marzo 11, 2026","format":"video","excerpt":"Los alumnos que actualmente est\u00e1n cursando el Diploma Dual en el Colegio Santa Teresa de Jes\u00fas El Vedat de Torrent nos cuentan su experiencia con el programa. Nos explican c\u00f3mo les ha ido durante el primer semestre del curso, lo que han aprendido y lo que m\u00e1s les ha gustado.\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"Colegio Santa Teresa de Jes\u00fas El Vedat Valencia","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/02\/diploma-dual-colegio-el-vedat.png?fit=802%2C1104&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/02\/diploma-dual-colegio-el-vedat.png?fit=802%2C1104&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/02\/diploma-dual-colegio-el-vedat.png?fit=802%2C1104&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/02\/diploma-dual-colegio-el-vedat.png?fit=802%2C1104&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":4501,"url":"https:\/\/www.academica.school\/news\/colegio-santa-teresa-cabeza-del-buey-ofrecera-diploma-dual\/","url_meta":{"origin":2927,"position":2},"title":"El Colegio Santa Teresa de Cabeza del Buey ofrecer\u00e1 el Diploma Dual a partir del pr\u00f3ximo curso","author":"Academica Spain","date":"junio 17, 2026","format":false,"excerpt":"El Colegio Santa Teresa de Cabeza del Buey ya forma parte de los m\u00e1s de 1.000 colegios adheridos al programa Diploma Dual en Espa\u00f1a y Portugal. De esta forma, el colegio ofrece a sus alumnos la posibilidad de obtener dos titulaciones de forma simult\u00e1nea: la propia de su pa\u00eds y\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"Visita Colegio Santa Teresa Cabeza del Buey","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/06\/diploma-dual-colegio-santa-teresa.jpg?fit=900%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/06\/diploma-dual-colegio-santa-teresa.jpg?fit=900%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/06\/diploma-dual-colegio-santa-teresa.jpg?fit=900%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/06\/diploma-dual-colegio-santa-teresa.jpg?fit=900%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2416,"url":"https:\/\/www.academica.school\/news\/el-diploma-dual-me-ha-ensenado-a-organizar-mejor-mis-estudios\/","url_meta":{"origin":2927,"position":3},"title":"\u00abEl Diploma Dual me ha ense\u00f1ado a organizar mejor mis estudios\u00bb","author":"Academica Spain","date":"mayo 8, 2024","format":false,"excerpt":"Vera est\u00e1 cursando 3\u00ba de la ESO en el Colegio Santa Teresa de Jes\u00fas de Salamanca y est\u00e1 haciendo al mismo tiempo el Diploma Dual. Est\u00e1n siendo unos a\u00f1os de gran aprendizaje para ella, en los que no s\u00f3lo est\u00e1 mejorando sus destrezas en el ingl\u00e9s, sino que le est\u00e1\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"colegio-santa-teresa-de-jesus-salamanca-diploma-dual-academica","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2024\/05\/Testimonio-Vera-scaled-e1715160467406.jpg?fit=530%2C648&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2024\/05\/Testimonio-Vera-scaled-e1715160467406.jpg?fit=530%2C648&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2024\/05\/Testimonio-Vera-scaled-e1715160467406.jpg?fit=530%2C648&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":4359,"url":"https:\/\/www.academica.school\/news\/santa-teresa-ganduxer-celebra-15-anos-exito-diploma-dual\/","url_meta":{"origin":2927,"position":4},"title":"El Col\u00b7legi Santa Teresa Ganduxer de Barcelona celebra 15 a\u00f1os de \u00e9xito con el Diploma Dual","author":"Academica Spain","date":"abril 29, 2026","format":false,"excerpt":"Hemos tenido el placer de visitar el Col\u00b7legi Santa Teresa Ganduxer de Barcelona, donde fuimos recibidos por el equipo directivo y de coordinaci\u00f3n del programa, a quienes agradecemos su c\u00e1lida acogida y la oportunidad de conocer de cerca el excelente trabajo que realizan. Durante la visita pudimos comprobar el firme\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"Visita Col\u00b7legi Santa Teresa Ganduxer de Barcelona","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/04\/diploma-dual-santa-teresa-ganduxer-2-e1777448702858.jpeg?fit=1000%2C810&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/04\/diploma-dual-santa-teresa-ganduxer-2-e1777448702858.jpeg?fit=1000%2C810&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/04\/diploma-dual-santa-teresa-ganduxer-2-e1777448702858.jpeg?fit=1000%2C810&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/04\/diploma-dual-santa-teresa-ganduxer-2-e1777448702858.jpeg?fit=1000%2C810&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2420,"url":"https:\/\/www.academica.school\/news\/el-diploma-dual-esta-siendo-una-experiencia-muy-util-e-interesante\/","url_meta":{"origin":2927,"position":5},"title":"\u00abEl Diploma Dual est\u00e1 siendo una experiencia muy \u00fatil e interesante\u00bb","author":"Academica Spain","date":"mayo 16, 2024","format":false,"excerpt":"Mar\u00eda est\u00e1 cursando 3\u00ba de la ESO en el Colegio Santa Teresa de Jes\u00fas de Salamanca y est\u00e1 haciendo al mismo tiempo el Diploma Dual. A continuaci\u00f3n, Mar\u00eda nos cuenta lo que est\u00e1 suponiendo para ella cursar el programa y todo lo que est\u00e1 aprendiendo. Mar\u00eda nos cuenta: \u00abEmpec\u00e9 con\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"colegio-santa-teresa-de-jesus-salamanca-diploma-dual-academica","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2024\/05\/Testimonio-Maria-G-e1715167392387.jpg?fit=530%2C707&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2024\/05\/Testimonio-Maria-G-e1715167392387.jpg?fit=530%2C707&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2024\/05\/Testimonio-Maria-G-e1715167392387.jpg?fit=530%2C707&ssl=1&resize=525%2C300 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/posts\/2927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/comments?post=2927"}],"version-history":[{"count":2,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/posts\/2927\/revisions"}],"predecessor-version":[{"id":2946,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/posts\/2927\/revisions\/2946"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/media\/2929"}],"wp:attachment":[{"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/media?parent=2927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/categories?post=2927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/tags?post=2927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}