{"id":2991,"date":"2025-02-27T11:14:15","date_gmt":"2025-02-27T11:14:15","guid":{"rendered":"https:\/\/www.academica.school\/news\/?p=2991"},"modified":"2025-02-27T11:14:15","modified_gmt":"2025-02-27T11:14:15","slug":"apertura-de-la-universidad-publica-estadounidense-a-los-alumnos-espanoles","status":"publish","type":"post","link":"https:\/\/www.academica.school\/news\/apertura-de-la-universidad-publica-estadounidense-a-los-alumnos-espanoles\/","title":{"rendered":"Apertura de la Universidad P\u00fablica estadounidense a los alumnos espa\u00f1oles"},"content":{"rendered":"<div class=\"\">\n<p>El <strong>pr\u00f3ximo martes 4 de marzo a las 20 horas<\/strong> tendr\u00e1 lugar la primera videoconferencia en la que contaremos con la participaci\u00f3n de Mr. Manny D\u00edaz Jr., Ministro de Educaci\u00f3n del Estado de La Florida y, Madeline Pumariega, Presidenta de Miami Dade College.<\/p>\n<p><!--more--><\/p>\n<\/div>\n<div class=\"\">\n<div class=\"\">\n<div class=\"\">\n<div class=\"elementor-widget-container\">\n<p>A lo largo de este curso estamos teniendo la oportunidad de conocer a distintas universidades en las nuevas <span style=\"text-decoration: underline;\"><span style=\"color: #0000ff; text-decoration: underline;\"><strong><a style=\"color: #0000ff; text-decoration: underline;\" href=\"https:\/\/www.academica.school\/university\">Jornadas Academica University Around The World<\/a><\/strong><\/span><\/span> dirigidas a todos los alumnos desde 3\u00ba de la ESO hasta 2\u00ba de Bachillerato. Se trata de videoconferencias dirigidas a los alumnos para que dispongan de un espacio de encuentro, conocimiento, orientaci\u00f3n, oportunidades y contacto con la universidad y sus profesionales.<\/p>\n<p>Desde Academica queremos seguir apoyando la gran labor educativa y de orientaci\u00f3n que se lleva a cabo desde los centros escolares, inculc\u00e1ndoles a los alumnos los valores del esfuerzo y trabajo diario. Por eso, tenemos el placer de anunciar que la Universidad P\u00fablica estadounidense se abre a los alumnos espa\u00f1oles. Esta colaboraci\u00f3n representa un compromiso compartido con la esperanza, la oportunidad y la creaci\u00f3n de conexiones internacionales.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo martes 4 de marzo a las 20 horas tendr\u00e1 lugar la primera videoconferencia en la que contaremos con la participaci\u00f3n de Mr. Manny D\u00edaz Jr., Ministro de Educaci\u00f3n del Estado de La Florida y, Madeline Pumariega, Presidenta de Miami Dade College.<\/p>\n","protected":false},"author":6,"featured_media":2992,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[9,139,104,89,198,63,208,4,222,431,714],"class_list":["post-2991","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-last-news","tag-academica","tag-academica-spain","tag-academica-university","tag-alumnos","tag-american-high-school","tag-bachillerato-americano","tag-colegio","tag-diploma-dual","tag-dual-diploma","tag-los-300-mejores","tag-miami-dade-college","clearfix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Apertura de la Universidad P\u00fablica estadounidense a los alumnos espa\u00f1oles - Academica News<\/title>\n<meta name=\"description\" content=\"El pr\u00f3ximo martes 4 de marzo a las 20 horas tendr\u00e1 lugar la primera videoconferencia con la participaci\u00f3n de Mr. Manny D\u00edaz Jr.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.academica.school\/news\/apertura-de-la-universidad-publica-estadounidense-a-los-alumnos-espanoles\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apertura de la Universidad P\u00fablica estadounidense a los alumnos espa\u00f1oles - Academica News\" \/>\n<meta property=\"og:description\" content=\"El pr\u00f3ximo martes 4 de marzo a las 20 horas tendr\u00e1 lugar la primera videoconferencia con la participaci\u00f3n de Mr. Manny D\u00edaz Jr.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.academica.school\/news\/apertura-de-la-universidad-publica-estadounidense-a-los-alumnos-espanoles\/\" \/>\n<meta property=\"og:site_name\" content=\"Academica News\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-27T11:14:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.academica.school\/news\/wp-content\/uploads\/2025\/02\/diploma-dual-academica-4.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1212\" \/>\n\t<meta property=\"og:image:height\" content=\"732\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Academica Spain\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Academica Spain\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/apertura-de-la-universidad-publica-estadounidense-a-los-alumnos-espanoles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/apertura-de-la-universidad-publica-estadounidense-a-los-alumnos-espanoles\\\/\"},\"author\":{\"name\":\"Academica Spain\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#\\\/schema\\\/person\\\/a9da1d35195720e471d7993db5fa06cd\"},\"headline\":\"Apertura de la Universidad P\u00fablica estadounidense a los alumnos espa\u00f1oles\",\"datePublished\":\"2025-02-27T11:14:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/apertura-de-la-universidad-publica-estadounidense-a-los-alumnos-espanoles\\\/\"},\"wordCount\":194,\"publisher\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/apertura-de-la-universidad-publica-estadounidense-a-los-alumnos-espanoles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/diploma-dual-academica-4.png?fit=1212%2C732&ssl=1\",\"keywords\":[\"academica\",\"academica spain\",\"academica university\",\"alumnos\",\"american high school\",\"bachillerato americano\",\"colegio\",\"Diploma Dual\",\"dual diploma\",\"los 300 mejores\",\"Miami dade college\"],\"articleSection\":[\"Last News\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/apertura-de-la-universidad-publica-estadounidense-a-los-alumnos-espanoles\\\/\",\"url\":\"https:\\\/\\\/www.academica.school\\\/news\\\/apertura-de-la-universidad-publica-estadounidense-a-los-alumnos-espanoles\\\/\",\"name\":\"Apertura de la Universidad P\u00fablica estadounidense a los alumnos espa\u00f1oles - Academica News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/apertura-de-la-universidad-publica-estadounidense-a-los-alumnos-espanoles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/apertura-de-la-universidad-publica-estadounidense-a-los-alumnos-espanoles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/diploma-dual-academica-4.png?fit=1212%2C732&ssl=1\",\"datePublished\":\"2025-02-27T11:14:15+00:00\",\"description\":\"El pr\u00f3ximo martes 4 de marzo a las 20 horas tendr\u00e1 lugar la primera videoconferencia con la participaci\u00f3n de Mr. Manny D\u00edaz Jr.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/apertura-de-la-universidad-publica-estadounidense-a-los-alumnos-espanoles\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.academica.school\\\/news\\\/apertura-de-la-universidad-publica-estadounidense-a-los-alumnos-espanoles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/apertura-de-la-universidad-publica-estadounidense-a-los-alumnos-espanoles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/diploma-dual-academica-4.png?fit=1212%2C732&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/diploma-dual-academica-4.png?fit=1212%2C732&ssl=1\",\"width\":1212,\"height\":732,\"caption\":\"diploma-dual-academica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/apertura-de-la-universidad-publica-estadounidense-a-los-alumnos-espanoles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.academica.school\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apertura de la Universidad P\u00fablica estadounidense a los alumnos espa\u00f1oles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/www.academica.school\\\/news\\\/\",\"name\":\"Academica News\",\"description\":\"todo lo que pasa en el mundo acad\u00e9mico, sobre universidades y cualquier evento o novedad en la que participemos\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.academica.school\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#organization\",\"name\":\"Academica\",\"url\":\"https:\\\/\\\/www.academica.school\\\/news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Captura-de-pantalla-2019-11-20-a-las-12.14.04.png?fit=799%2C500&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Captura-de-pantalla-2019-11-20-a-las-12.14.04.png?fit=799%2C500&ssl=1\",\"width\":799,\"height\":500,\"caption\":\"Academica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#\\\/schema\\\/person\\\/a9da1d35195720e471d7993db5fa06cd\",\"name\":\"Academica Spain\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7ed0e6b5e69a0c89f30117b1b70787c4c8d25c0438514a94ac82dee11b08589?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7ed0e6b5e69a0c89f30117b1b70787c4c8d25c0438514a94ac82dee11b08589?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7ed0e6b5e69a0c89f30117b1b70787c4c8d25c0438514a94ac82dee11b08589?s=96&d=mm&r=g\",\"caption\":\"Academica Spain\"},\"url\":\"https:\\\/\\\/www.academica.school\\\/news\\\/author\\\/pquecedoacademica-school\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Apertura de la Universidad P\u00fablica estadounidense a los alumnos espa\u00f1oles - Academica News","description":"El pr\u00f3ximo martes 4 de marzo a las 20 horas tendr\u00e1 lugar la primera videoconferencia con la participaci\u00f3n de Mr. Manny D\u00edaz Jr.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.academica.school\/news\/apertura-de-la-universidad-publica-estadounidense-a-los-alumnos-espanoles\/","og_locale":"es_ES","og_type":"article","og_title":"Apertura de la Universidad P\u00fablica estadounidense a los alumnos espa\u00f1oles - Academica News","og_description":"El pr\u00f3ximo martes 4 de marzo a las 20 horas tendr\u00e1 lugar la primera videoconferencia con la participaci\u00f3n de Mr. Manny D\u00edaz Jr.","og_url":"https:\/\/www.academica.school\/news\/apertura-de-la-universidad-publica-estadounidense-a-los-alumnos-espanoles\/","og_site_name":"Academica News","article_published_time":"2025-02-27T11:14:15+00:00","og_image":[{"width":1212,"height":732,"url":"https:\/\/www.academica.school\/news\/wp-content\/uploads\/2025\/02\/diploma-dual-academica-4.png","type":"image\/png"}],"author":"Academica Spain","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Academica Spain","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.academica.school\/news\/apertura-de-la-universidad-publica-estadounidense-a-los-alumnos-espanoles\/#article","isPartOf":{"@id":"https:\/\/www.academica.school\/news\/apertura-de-la-universidad-publica-estadounidense-a-los-alumnos-espanoles\/"},"author":{"name":"Academica Spain","@id":"https:\/\/www.academica.school\/news\/#\/schema\/person\/a9da1d35195720e471d7993db5fa06cd"},"headline":"Apertura de la Universidad P\u00fablica estadounidense a los alumnos espa\u00f1oles","datePublished":"2025-02-27T11:14:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.academica.school\/news\/apertura-de-la-universidad-publica-estadounidense-a-los-alumnos-espanoles\/"},"wordCount":194,"publisher":{"@id":"https:\/\/www.academica.school\/news\/#organization"},"image":{"@id":"https:\/\/www.academica.school\/news\/apertura-de-la-universidad-publica-estadounidense-a-los-alumnos-espanoles\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/02\/diploma-dual-academica-4.png?fit=1212%2C732&ssl=1","keywords":["academica","academica spain","academica university","alumnos","american high school","bachillerato americano","colegio","Diploma Dual","dual diploma","los 300 mejores","Miami dade college"],"articleSection":["Last News"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.academica.school\/news\/apertura-de-la-universidad-publica-estadounidense-a-los-alumnos-espanoles\/","url":"https:\/\/www.academica.school\/news\/apertura-de-la-universidad-publica-estadounidense-a-los-alumnos-espanoles\/","name":"Apertura de la Universidad P\u00fablica estadounidense a los alumnos espa\u00f1oles - Academica News","isPartOf":{"@id":"https:\/\/www.academica.school\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.academica.school\/news\/apertura-de-la-universidad-publica-estadounidense-a-los-alumnos-espanoles\/#primaryimage"},"image":{"@id":"https:\/\/www.academica.school\/news\/apertura-de-la-universidad-publica-estadounidense-a-los-alumnos-espanoles\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/02\/diploma-dual-academica-4.png?fit=1212%2C732&ssl=1","datePublished":"2025-02-27T11:14:15+00:00","description":"El pr\u00f3ximo martes 4 de marzo a las 20 horas tendr\u00e1 lugar la primera videoconferencia con la participaci\u00f3n de Mr. Manny D\u00edaz Jr.","breadcrumb":{"@id":"https:\/\/www.academica.school\/news\/apertura-de-la-universidad-publica-estadounidense-a-los-alumnos-espanoles\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.academica.school\/news\/apertura-de-la-universidad-publica-estadounidense-a-los-alumnos-espanoles\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.academica.school\/news\/apertura-de-la-universidad-publica-estadounidense-a-los-alumnos-espanoles\/#primaryimage","url":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/02\/diploma-dual-academica-4.png?fit=1212%2C732&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/02\/diploma-dual-academica-4.png?fit=1212%2C732&ssl=1","width":1212,"height":732,"caption":"diploma-dual-academica"},{"@type":"BreadcrumbList","@id":"https:\/\/www.academica.school\/news\/apertura-de-la-universidad-publica-estadounidense-a-los-alumnos-espanoles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.academica.school\/news\/"},{"@type":"ListItem","position":2,"name":"Apertura de la Universidad P\u00fablica estadounidense a los alumnos espa\u00f1oles"}]},{"@type":"WebSite","@id":"https:\/\/www.academica.school\/news\/#website","url":"https:\/\/www.academica.school\/news\/","name":"Academica News","description":"todo lo que pasa en el mundo acad\u00e9mico, sobre universidades y cualquier evento o novedad en la que participemos","publisher":{"@id":"https:\/\/www.academica.school\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.academica.school\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.academica.school\/news\/#organization","name":"Academica","url":"https:\/\/www.academica.school\/news\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.academica.school\/news\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2019\/11\/Captura-de-pantalla-2019-11-20-a-las-12.14.04.png?fit=799%2C500&ssl=1","contentUrl":"https:\/\/i1.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2019\/11\/Captura-de-pantalla-2019-11-20-a-las-12.14.04.png?fit=799%2C500&ssl=1","width":799,"height":500,"caption":"Academica"},"image":{"@id":"https:\/\/www.academica.school\/news\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.academica.school\/news\/#\/schema\/person\/a9da1d35195720e471d7993db5fa06cd","name":"Academica Spain","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a7ed0e6b5e69a0c89f30117b1b70787c4c8d25c0438514a94ac82dee11b08589?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a7ed0e6b5e69a0c89f30117b1b70787c4c8d25c0438514a94ac82dee11b08589?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a7ed0e6b5e69a0c89f30117b1b70787c4c8d25c0438514a94ac82dee11b08589?s=96&d=mm&r=g","caption":"Academica Spain"},"url":"https:\/\/www.academica.school\/news\/author\/pquecedoacademica-school\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/02\/diploma-dual-academica-4.png?fit=1212%2C732&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8RDKh-Mf","jetpack-related-posts":[{"id":3167,"url":"https:\/\/www.academica.school\/news\/estudiar-en-los-estados-unidos\/","url_meta":{"origin":2991,"position":0},"title":"Estudiar en los Estados Unidos","author":"Academica Spain","date":"abril 28, 2025","format":false,"excerpt":"El lunes 5 de mayo a las 20 horas tendr\u00e1 lugar una nueva videoconferencia en la que todos los alumnos espa\u00f1oles tendr\u00e1n la posibilidad de conocer la Universidad P\u00fablica estadounidense. Desde la direcci\u00f3n de admisiones de Miami Dade College se realizar\u00e1 una presentaci\u00f3n de los estudios de la Universidad P\u00fablica\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"diploma-dual-universidad-publica-usa","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/03\/diploma-dual-academica-2.jpg?fit=1000%2C667&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/03\/diploma-dual-academica-2.jpg?fit=1000%2C667&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/03\/diploma-dual-academica-2.jpg?fit=1000%2C667&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/03\/diploma-dual-academica-2.jpg?fit=1000%2C667&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":3023,"url":"https:\/\/www.academica.school\/news\/conoce-las-oportunidades-de-estudiar-en-la-universidad-publica-estadounidense\/","url_meta":{"origin":2991,"position":1},"title":"Conoce las oportunidades de estudiar en la Universidad P\u00fablica estadounidense","author":"Academica Spain","date":"marzo 12, 2025","format":false,"excerpt":"El pr\u00f3ximo mi\u00e9rcoles 19 de marzo a las 20 horas tendr\u00e1 lugar una nueva videoconferencia en la que todos los alumnos espa\u00f1oles tendr\u00e1n la posibilidad de conocer las oportunidades de estudiar en la Universidad P\u00fablica estadounidense. Contaremos con la participaci\u00f3n del Dr. Jaime Anzalotta, Director General de Admisiones y Vicerrector\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"diploma-dual-universidad-publica-usa","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/03\/diploma-dual-academica-2.jpg?fit=1000%2C667&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/03\/diploma-dual-academica-2.jpg?fit=1000%2C667&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/03\/diploma-dual-academica-2.jpg?fit=1000%2C667&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/03\/diploma-dual-academica-2.jpg?fit=1000%2C667&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":3006,"url":"https:\/\/www.academica.school\/news\/presentacion-de-la-universidad-publica-estadounidense-a-los-alumnos-espanoles\/","url_meta":{"origin":2991,"position":2},"title":"Presentaci\u00f3n de la Universidad P\u00fablica estadounidense a los alumnos espa\u00f1oles","author":"Academica Spain","date":"marzo 4, 2025","format":false,"excerpt":"El diario ABC, perteneciente al Grupo Vocento, ha publicado una noticia para anunciar la presentaci\u00f3n que se va a realizar desde Academica de la Universidad P\u00fablica estadounidense a todos los alumnos espa\u00f1oles. La videoconferencia tendr\u00e1 lugar hoy martes 4 de marzo a las 20 horas peninsular y contaremos con la\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"diploma-dual-academica","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/03\/diploma-dual-academica.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/03\/diploma-dual-academica.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/03\/diploma-dual-academica.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/03\/diploma-dual-academica.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/03\/diploma-dual-academica.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":2369,"url":"https:\/\/www.academica.school\/news\/schiller-international-university-da-el-pistoletazo-de-salida-a-unas-nuevas-jornadas-dirigidas-a-los-alumnos-de-1o-de-bachillerato\/","url_meta":{"origin":2991,"position":3},"title":"Schiller International University da el pistoletazo de salida a unas nuevas jornadas dirigidas a los alumnos de 1\u00ba de Bachillerato","author":"Academica Spain","date":"abril 25, 2024","format":false,"excerpt":"A lo largo de las pr\u00f3ximas semanas vamos a tener la oportunidad de conocer a distintas universidades en las nuevas Jornadas Academica University Around The World dirigidas a todos los alumnos de 1\u00ba de Bachillerato. Desde Academica queremos seguir apoyando la gran labor educativa y de orientaci\u00f3n que se lleva\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"schiller-academica-university","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2024\/04\/SCHILLER-2.png?fit=1200%2C681&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2024\/04\/SCHILLER-2.png?fit=1200%2C681&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2024\/04\/SCHILLER-2.png?fit=1200%2C681&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2024\/04\/SCHILLER-2.png?fit=1200%2C681&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2024\/04\/SCHILLER-2.png?fit=1200%2C681&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":3438,"url":"https:\/\/www.academica.school\/news\/vuelven-las-jornadas-academica-university\/","url_meta":{"origin":2991,"position":4},"title":"Vuelven las Jornadas Academica University","author":"Academica Spain","date":"octubre 10, 2025","format":false,"excerpt":"Con mucha ilusi\u00f3n anunciamos el inicio de las jornadas con universidades de reconocido prestigio, que no s\u00f3lo valoran el m\u00e9rito y preparaci\u00f3n de los alumnos del Diploma Dual, sino que tambi\u00e9n ofrecer\u00e1n ventajas y oportunidades \u00fanicas para facilitar el acceso de los alumnos Class of 2026\u00a0a ellas. A lo largo\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"Graduaci\u00f3n Academica","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/10\/img-graduados_grad25-classof_academica-classof-25-162.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/10\/img-graduados_grad25-classof_academica-classof-25-162.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/10\/img-graduados_grad25-classof_academica-classof-25-162.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/10\/img-graduados_grad25-classof_academica-classof-25-162.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/10\/img-graduados_grad25-classof_academica-classof-25-162.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":2906,"url":"https:\/\/www.academica.school\/news\/cunef-organiza-una-mesa-redonda-con-sus-alumnos-en-las-jornadas-academica-university\/","url_meta":{"origin":2991,"position":5},"title":"CUNEF organiza una mesa redonda con sus alumnos en las Jornadas Academica University","author":"Academica Spain","date":"enero 31, 2025","format":false,"excerpt":"La Universidad CUNEF vuelve a estar presente en las Jornadas Academica University dirigidas a los alumnos de 2\u00ba de Bachillerato, donde hemos tenido el placer de contar con una sesi\u00f3n muy especial y motivadora. Hace unas semanas tuvimos la oportunidad de conocer la universidad de manera m\u00e1s cercana gracias a\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"diploma-dual-academica","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/01\/diploma-dual-academica-6.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/01\/diploma-dual-academica-6.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/01\/diploma-dual-academica-6.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/01\/diploma-dual-academica-6.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/01\/diploma-dual-academica-6.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/posts\/2991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/comments?post=2991"}],"version-history":[{"count":6,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/posts\/2991\/revisions"}],"predecessor-version":[{"id":2998,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/posts\/2991\/revisions\/2998"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/media\/2992"}],"wp:attachment":[{"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/media?parent=2991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/categories?post=2991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/tags?post=2991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}