{"id":3598,"date":"2025-11-06T09:24:25","date_gmt":"2025-11-06T09:24:25","guid":{"rendered":"https:\/\/www.academica.school\/news\/?p=3598"},"modified":"2025-11-10T14:12:49","modified_gmt":"2025-11-10T14:12:49","slug":"compromiso-futuro-alumnos-diploma-dual-salesianas-torrent","status":"publish","type":"post","link":"https:\/\/www.academica.school\/news\/compromiso-futuro-alumnos-diploma-dual-salesianas-torrent\/","title":{"rendered":"Compromiso con el futuro: Alumnos del Colegio Mar\u00eda Auxiliadora Salesianas de Torrent"},"content":{"rendered":"<p>Los alumnos que est\u00e1n cursando el Diploma Dual en el <span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"https:\/\/torrent.salesianas.org\"><span style=\"text-decoration: underline;\"><b>Colegio Mar\u00eda Auxiliadora Salesianas de Torrent<\/b><\/span><\/a><\/span> est\u00e1n demostrando un firme compromiso con su futuro.<\/p>\n<p><!--more--><\/p>\n<p data-start=\"1467\" data-end=\"1817\">Nos han recibido en el colegio Inmaculada, Directora del Centro, y Juliana, Directora de Programa, quienes han compartido con nosotros su visi\u00f3n y evoluci\u00f3n de los alumnos que est\u00e1n cursando el programa. Esto nos ha permitido conocer de primera mano el entorno educativo excepcional que ofrece el colegio a sus estudiantes.<\/p>\n<p data-start=\"1467\" data-end=\"1817\">Adem\u00e1s, hemos tenido la oportunidad de charlar un rato con las alumnas que est\u00e1n cursando el <span style=\"color: #000000;\"><strong>Diploma Dual<\/strong><\/span>, siendo testigos de las ganas que tienen de aprender y trabajar, lo que demuestra la gran madurez de todos ellos.<\/p>\n<p data-start=\"1467\" data-end=\"1817\">Es un orgullo ver las ganas que tienen todos de ser mejores y lograr sus objetivos.<\/p>\n<p data-start=\"1467\" data-end=\"1817\"><span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"https:\/\/www.instagram.com\/p\/DQol7WVDKnP\/?utm_source=ig_web_copy_link&amp;igsh=MzRlODBiNWFlZA==\"><span style=\"text-decoration: underline;\"><strong>Enlace<\/strong><\/span><\/a><\/span> a la publicaci\u00f3n del colegio. \u00a1Estate al tanto de todas sus noticias!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los alumnos que est\u00e1n cursando el Diploma Dual en el Colegio Mar\u00eda Auxiliadora Salesianas de Torrent est\u00e1n demostrando un firme compromiso con su futuro.<\/p>\n","protected":false},"author":6,"featured_media":3599,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[9,139,89,198,63,208,801,4,222,431],"class_list":["post-3598","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-last-news","tag-academica","tag-academica-spain","tag-alumnos","tag-american-high-school","tag-bachillerato-americano","tag-colegio","tag-colegio-maria-auxiliadora-salesianas","tag-diploma-dual","tag-dual-diploma","tag-los-300-mejores","clearfix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Compromiso con el futuro: Alumnos del Colegio Mar\u00eda Auxiliadora Salesianas de Torrent - Academica News<\/title>\n<meta name=\"description\" content=\"Los alumnos que est\u00e1n cursando el Diploma Dual en el Colegio Mar\u00eda Auxiliadora Salesianas de Torrent est\u00e1n demostrando un firme compromiso.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.academica.school\/news\/compromiso-futuro-alumnos-diploma-dual-salesianas-torrent\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Compromiso con el futuro: Alumnos del Colegio Mar\u00eda Auxiliadora Salesianas de Torrent - Academica News\" \/>\n<meta property=\"og:description\" content=\"Los alumnos que est\u00e1n cursando el Diploma Dual en el Colegio Mar\u00eda Auxiliadora Salesianas de Torrent est\u00e1n demostrando un firme compromiso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.academica.school\/news\/compromiso-futuro-alumnos-diploma-dual-salesianas-torrent\/\" \/>\n<meta property=\"og:site_name\" content=\"Academica News\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-06T09:24:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-10T14:12:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.academica.school\/news\/wp-content\/uploads\/2025\/11\/diploma-dual-salesianas-torrent-e1762421296955.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1352\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Academica Spain\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Academica Spain\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/compromiso-futuro-alumnos-diploma-dual-salesianas-torrent\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/compromiso-futuro-alumnos-diploma-dual-salesianas-torrent\\\/\"},\"author\":{\"name\":\"Academica Spain\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#\\\/schema\\\/person\\\/a9da1d35195720e471d7993db5fa06cd\"},\"headline\":\"Compromiso con el futuro: Alumnos del Colegio Mar\u00eda Auxiliadora Salesianas de Torrent\",\"datePublished\":\"2025-11-06T09:24:25+00:00\",\"dateModified\":\"2025-11-10T14:12:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/compromiso-futuro-alumnos-diploma-dual-salesianas-torrent\\\/\"},\"wordCount\":164,\"publisher\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/compromiso-futuro-alumnos-diploma-dual-salesianas-torrent\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/diploma-dual-salesianas-torrent-e1762421296955.jpg?fit=1200%2C1352&ssl=1\",\"keywords\":[\"academica\",\"academica spain\",\"alumnos\",\"american high school\",\"bachillerato americano\",\"colegio\",\"colegio maria auxiliadora salesianas\",\"Diploma Dual\",\"dual diploma\",\"los 300 mejores\"],\"articleSection\":[\"Last News\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/compromiso-futuro-alumnos-diploma-dual-salesianas-torrent\\\/\",\"url\":\"https:\\\/\\\/www.academica.school\\\/news\\\/compromiso-futuro-alumnos-diploma-dual-salesianas-torrent\\\/\",\"name\":\"Compromiso con el futuro: Alumnos del Colegio Mar\u00eda Auxiliadora Salesianas de Torrent - Academica News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/compromiso-futuro-alumnos-diploma-dual-salesianas-torrent\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/compromiso-futuro-alumnos-diploma-dual-salesianas-torrent\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/diploma-dual-salesianas-torrent-e1762421296955.jpg?fit=1200%2C1352&ssl=1\",\"datePublished\":\"2025-11-06T09:24:25+00:00\",\"dateModified\":\"2025-11-10T14:12:49+00:00\",\"description\":\"Los alumnos que est\u00e1n cursando el Diploma Dual en el Colegio Mar\u00eda Auxiliadora Salesianas de Torrent est\u00e1n demostrando un firme compromiso.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/compromiso-futuro-alumnos-diploma-dual-salesianas-torrent\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.academica.school\\\/news\\\/compromiso-futuro-alumnos-diploma-dual-salesianas-torrent\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/compromiso-futuro-alumnos-diploma-dual-salesianas-torrent\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/diploma-dual-salesianas-torrent-e1762421296955.jpg?fit=1200%2C1352&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/diploma-dual-salesianas-torrent-e1762421296955.jpg?fit=1200%2C1352&ssl=1\",\"width\":1200,\"height\":1352,\"caption\":\"Visita al Colegio Mar\u00eda Auxiliadora Salesianas Torrent\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/compromiso-futuro-alumnos-diploma-dual-salesianas-torrent\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.academica.school\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Compromiso con el futuro: Alumnos del Colegio Mar\u00eda Auxiliadora Salesianas de Torrent\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/www.academica.school\\\/news\\\/\",\"name\":\"Academica News\",\"description\":\"todo lo que pasa en el mundo acad\u00e9mico, sobre universidades y cualquier evento o novedad en la que participemos\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.academica.school\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#organization\",\"name\":\"Academica\",\"url\":\"https:\\\/\\\/www.academica.school\\\/news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Captura-de-pantalla-2019-11-20-a-las-12.14.04.png?fit=799%2C500&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Captura-de-pantalla-2019-11-20-a-las-12.14.04.png?fit=799%2C500&ssl=1\",\"width\":799,\"height\":500,\"caption\":\"Academica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#\\\/schema\\\/person\\\/a9da1d35195720e471d7993db5fa06cd\",\"name\":\"Academica Spain\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7ed0e6b5e69a0c89f30117b1b70787c4c8d25c0438514a94ac82dee11b08589?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7ed0e6b5e69a0c89f30117b1b70787c4c8d25c0438514a94ac82dee11b08589?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7ed0e6b5e69a0c89f30117b1b70787c4c8d25c0438514a94ac82dee11b08589?s=96&d=mm&r=g\",\"caption\":\"Academica Spain\"},\"url\":\"https:\\\/\\\/www.academica.school\\\/news\\\/author\\\/pquecedoacademica-school\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Compromiso con el futuro: Alumnos del Colegio Mar\u00eda Auxiliadora Salesianas de Torrent - Academica News","description":"Los alumnos que est\u00e1n cursando el Diploma Dual en el Colegio Mar\u00eda Auxiliadora Salesianas de Torrent est\u00e1n demostrando un firme compromiso.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.academica.school\/news\/compromiso-futuro-alumnos-diploma-dual-salesianas-torrent\/","og_locale":"es_ES","og_type":"article","og_title":"Compromiso con el futuro: Alumnos del Colegio Mar\u00eda Auxiliadora Salesianas de Torrent - Academica News","og_description":"Los alumnos que est\u00e1n cursando el Diploma Dual en el Colegio Mar\u00eda Auxiliadora Salesianas de Torrent est\u00e1n demostrando un firme compromiso.","og_url":"https:\/\/www.academica.school\/news\/compromiso-futuro-alumnos-diploma-dual-salesianas-torrent\/","og_site_name":"Academica News","article_published_time":"2025-11-06T09:24:25+00:00","article_modified_time":"2025-11-10T14:12:49+00:00","og_image":[{"width":1200,"height":1352,"url":"https:\/\/www.academica.school\/news\/wp-content\/uploads\/2025\/11\/diploma-dual-salesianas-torrent-e1762421296955.jpg","type":"image\/jpeg"}],"author":"Academica Spain","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Academica Spain","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.academica.school\/news\/compromiso-futuro-alumnos-diploma-dual-salesianas-torrent\/#article","isPartOf":{"@id":"https:\/\/www.academica.school\/news\/compromiso-futuro-alumnos-diploma-dual-salesianas-torrent\/"},"author":{"name":"Academica Spain","@id":"https:\/\/www.academica.school\/news\/#\/schema\/person\/a9da1d35195720e471d7993db5fa06cd"},"headline":"Compromiso con el futuro: Alumnos del Colegio Mar\u00eda Auxiliadora Salesianas de Torrent","datePublished":"2025-11-06T09:24:25+00:00","dateModified":"2025-11-10T14:12:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.academica.school\/news\/compromiso-futuro-alumnos-diploma-dual-salesianas-torrent\/"},"wordCount":164,"publisher":{"@id":"https:\/\/www.academica.school\/news\/#organization"},"image":{"@id":"https:\/\/www.academica.school\/news\/compromiso-futuro-alumnos-diploma-dual-salesianas-torrent\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/11\/diploma-dual-salesianas-torrent-e1762421296955.jpg?fit=1200%2C1352&ssl=1","keywords":["academica","academica spain","alumnos","american high school","bachillerato americano","colegio","colegio maria auxiliadora salesianas","Diploma Dual","dual diploma","los 300 mejores"],"articleSection":["Last News"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.academica.school\/news\/compromiso-futuro-alumnos-diploma-dual-salesianas-torrent\/","url":"https:\/\/www.academica.school\/news\/compromiso-futuro-alumnos-diploma-dual-salesianas-torrent\/","name":"Compromiso con el futuro: Alumnos del Colegio Mar\u00eda Auxiliadora Salesianas de Torrent - Academica News","isPartOf":{"@id":"https:\/\/www.academica.school\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.academica.school\/news\/compromiso-futuro-alumnos-diploma-dual-salesianas-torrent\/#primaryimage"},"image":{"@id":"https:\/\/www.academica.school\/news\/compromiso-futuro-alumnos-diploma-dual-salesianas-torrent\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/11\/diploma-dual-salesianas-torrent-e1762421296955.jpg?fit=1200%2C1352&ssl=1","datePublished":"2025-11-06T09:24:25+00:00","dateModified":"2025-11-10T14:12:49+00:00","description":"Los alumnos que est\u00e1n cursando el Diploma Dual en el Colegio Mar\u00eda Auxiliadora Salesianas de Torrent est\u00e1n demostrando un firme compromiso.","breadcrumb":{"@id":"https:\/\/www.academica.school\/news\/compromiso-futuro-alumnos-diploma-dual-salesianas-torrent\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.academica.school\/news\/compromiso-futuro-alumnos-diploma-dual-salesianas-torrent\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.academica.school\/news\/compromiso-futuro-alumnos-diploma-dual-salesianas-torrent\/#primaryimage","url":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/11\/diploma-dual-salesianas-torrent-e1762421296955.jpg?fit=1200%2C1352&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/11\/diploma-dual-salesianas-torrent-e1762421296955.jpg?fit=1200%2C1352&ssl=1","width":1200,"height":1352,"caption":"Visita al Colegio Mar\u00eda Auxiliadora Salesianas Torrent"},{"@type":"BreadcrumbList","@id":"https:\/\/www.academica.school\/news\/compromiso-futuro-alumnos-diploma-dual-salesianas-torrent\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.academica.school\/news\/"},{"@type":"ListItem","position":2,"name":"Compromiso con el futuro: Alumnos del Colegio Mar\u00eda Auxiliadora Salesianas de Torrent"}]},{"@type":"WebSite","@id":"https:\/\/www.academica.school\/news\/#website","url":"https:\/\/www.academica.school\/news\/","name":"Academica News","description":"todo lo que pasa en el mundo acad\u00e9mico, sobre universidades y cualquier evento o novedad en la que participemos","publisher":{"@id":"https:\/\/www.academica.school\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.academica.school\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.academica.school\/news\/#organization","name":"Academica","url":"https:\/\/www.academica.school\/news\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.academica.school\/news\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2019\/11\/Captura-de-pantalla-2019-11-20-a-las-12.14.04.png?fit=799%2C500&ssl=1","contentUrl":"https:\/\/i1.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2019\/11\/Captura-de-pantalla-2019-11-20-a-las-12.14.04.png?fit=799%2C500&ssl=1","width":799,"height":500,"caption":"Academica"},"image":{"@id":"https:\/\/www.academica.school\/news\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.academica.school\/news\/#\/schema\/person\/a9da1d35195720e471d7993db5fa06cd","name":"Academica Spain","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a7ed0e6b5e69a0c89f30117b1b70787c4c8d25c0438514a94ac82dee11b08589?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a7ed0e6b5e69a0c89f30117b1b70787c4c8d25c0438514a94ac82dee11b08589?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a7ed0e6b5e69a0c89f30117b1b70787c4c8d25c0438514a94ac82dee11b08589?s=96&d=mm&r=g","caption":"Academica Spain"},"url":"https:\/\/www.academica.school\/news\/author\/pquecedoacademica-school\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/11\/diploma-dual-salesianas-torrent-e1762421296955.jpg?fit=1200%2C1352&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8RDKh-W2","jetpack-related-posts":[{"id":3759,"url":"https:\/\/www.academica.school\/news\/excelencia-educativa-colegio-maria-auxiliadora-salesianas-de-telde\/","url_meta":{"origin":3598,"position":0},"title":"Excelencia educativa: Colegio Mar\u00eda Auxiliadora Salesianas de Telde","author":"Academica Spain","date":"diciembre 4, 2025","format":false,"excerpt":"Nos desplazamos al Colegio Mar\u00eda Auxiliadora Salesianas de Telde para conocer el progreso de los alumnos que est\u00e1n cursando el Diploma Dual. El centro destaca por su apuesta por una educaci\u00f3n innovadora, basada en el acompa\u00f1amiento cercano y la creaci\u00f3n de entornos que favorecen el aprendizaje significativo. La forma en\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"Visita al Colegio Mar\u00eda Auxiliadora Salesianas de Telde","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/12\/diploma-dual-salesianas-telda-e1764857600727.jpg?fit=1200%2C1130&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/12\/diploma-dual-salesianas-telda-e1764857600727.jpg?fit=1200%2C1130&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/12\/diploma-dual-salesianas-telda-e1764857600727.jpg?fit=1200%2C1130&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/12\/diploma-dual-salesianas-telda-e1764857600727.jpg?fit=1200%2C1130&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/12\/diploma-dual-salesianas-telda-e1764857600727.jpg?fit=1200%2C1130&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":2007,"url":"https:\/\/www.academica.school\/news\/los-alumnos-del-colegio-maria-auxilidora-de-alicante-celebran-accion-de-gracias\/","url_meta":{"origin":3598,"position":1},"title":"Los alumnos del Colegio Mar\u00eda Auxilidora de Alicante celebran Acci\u00f3n de Gracias","author":"Academica Spain","date":"diciembre 13, 2023","format":false,"excerpt":"El Colegio Mar\u00eda Auxiliadora - Salesianas de Alicante no quiso dejar pasar la oportunidad de celebrar el D\u00eda de Acci\u00f3n de Gracias en el colegio con los alumnos del Diploma Dual. El Thanksgiving Day es un d\u00eda muy remarcado para los estadounidenses, no s\u00f3lo por la historia que hay detr\u00e1s,\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"DIPLOMA DUAL ACADEMICA","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2023\/12\/diploma-dual-salesianas-3-e1702481151685.jpg?fit=375%2C309&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3800,"url":"https:\/\/www.academica.school\/news\/alumnos-diploma-dual-aprenden-mejoran-nivel-ingles\/","url_meta":{"origin":3598,"position":2},"title":"\u00abLos alumnos del Diploma Dual aprenden y mejoran su nivel de ingl\u00e9s en situaciones reales al 100%\u00bb","author":"Academica Spain","date":"febrero 2, 2026","format":false,"excerpt":"Entrevistamos a Marta Dugo, Directora de Programa en el Colegio Mar\u00eda Auxiliadora Salesianas \u00c9cija de Sevilla,\u00a0quien nos cuenta su experiencia con el programa. Marta ha comenzado este a\u00f1o a encargarse del Diploma Dual en el centro. \u00bfQu\u00e9 tipo de tareas lleva impl\u00edcita esta responsabilidad para los que sois Directores de\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"Entrevista Directora de Programa Colegio Mar\u00eda Auxiliadora Salesianas \u00c9cija de Sevilla","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/12\/diploma-dual-salesianas-ecija.jpg?fit=425%2C510&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4080,"url":"https:\/\/www.academica.school\/news\/diploma-dual-abre-mente-alumnos-favorecer-tolerancia-respeto-culturas\/","url_meta":{"origin":3598,"position":3},"title":"\u00abEl Diploma Dual les abre mente a los alumnos, adem\u00e1s de favorecer la tolerancia y el respeto por las culturas\u00bb","author":"Academica Spain","date":"abril 13, 2026","format":false,"excerpt":"Entrevistamos a Beatriz Arcos, Directora de Programa en el Colegio Mar\u00eda Auxiliadora Salesianas San Vicente de Sevilla,\u00a0quien nos cuenta su experiencia con el programa. Beatriz comenz\u00f3 a encargarse del Diploma Dual en el centro a lo largo del curso pasado. \u00bfQu\u00e9 tipo de tareas lleva impl\u00edcita esta responsabilidad para los\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"Visita Colegio Mar\u00eda Auxiliadora Salesianas San Vicente Sevilla","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/02\/diploma-dual-salesianas-san-vicente-2-e1776066126896.jpeg?fit=700%2C933&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/02\/diploma-dual-salesianas-san-vicente-2-e1776066126896.jpeg?fit=700%2C933&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/02\/diploma-dual-salesianas-san-vicente-2-e1776066126896.jpeg?fit=700%2C933&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/02\/diploma-dual-salesianas-san-vicente-2-e1776066126896.jpeg?fit=700%2C933&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":4512,"url":"https:\/\/www.academica.school\/news\/escuelas-salesianas-maria-auxiliadora-sevilla-ofrecera-diploma-dual\/","url_meta":{"origin":3598,"position":4},"title":"El centro Escuelas Salesianas Mar\u00eda Auxiliadora de Sevilla ofrecer\u00e1 el Diploma Dual a partir del pr\u00f3ximo curso","author":"Academica Spain","date":"junio 22, 2026","format":false,"excerpt":"El centro Escuelas Salesianas Mar\u00eda Auxiliadora de Sevilla ya forma parte de los m\u00e1s de 1.000 colegios adheridos al programa Diploma Dual en Espa\u00f1a y Portugal. De esta forma, el colegio ofrece a sus alumnos la posibilidad de obtener dos titulaciones de forma simult\u00e1nea: la propia de su pa\u00eds y\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"Visita Escuelas Salesianas Mar\u00eda Auxiliadora Sevilla","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/06\/8286d01b-df4f-4b7a-b554-311b7925631b-e1782113078498.jpg?fit=1200%2C1060&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/06\/8286d01b-df4f-4b7a-b554-311b7925631b-e1782113078498.jpg?fit=1200%2C1060&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/06\/8286d01b-df4f-4b7a-b554-311b7925631b-e1782113078498.jpg?fit=1200%2C1060&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/06\/8286d01b-df4f-4b7a-b554-311b7925631b-e1782113078498.jpg?fit=1200%2C1060&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/06\/8286d01b-df4f-4b7a-b554-311b7925631b-e1782113078498.jpg?fit=1200%2C1060&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":3720,"url":"https:\/\/www.academica.school\/news\/futuro-diploma-dual-colegio-ntra-sra-pilar-salesianas-las-palmas\/","url_meta":{"origin":3598,"position":5},"title":"Una puerta al futuro: el Diploma Dual en el Colegio Nuestra Se\u00f1ora del Pilar Salesianas de Las Palmas","author":"Academica Spain","date":"diciembre 2, 2025","format":false,"excerpt":"Hemos tenido la oportunidad de visitar el Colegio Nuestra Se\u00f1ora del Pilar Salesianas de Las Palmas de Gran Canaria para ver de cerca el trabajo excepcional que est\u00e1n llevando a cabo los alumnos del Diploma Dual. Ha sido una experiencia muy enriquecedora, donde hemos podido ver c\u00f3mo el colegio est\u00e1\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"Visita al Colegio Nuestra Se\u00f1ora del Pilar Salesianas de Las Palmas","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/12\/diploma-dual-salesianas-ntra-sra-pilar-e1764601385552.jpg?fit=1200%2C1133&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/12\/diploma-dual-salesianas-ntra-sra-pilar-e1764601385552.jpg?fit=1200%2C1133&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/12\/diploma-dual-salesianas-ntra-sra-pilar-e1764601385552.jpg?fit=1200%2C1133&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/12\/diploma-dual-salesianas-ntra-sra-pilar-e1764601385552.jpg?fit=1200%2C1133&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/12\/diploma-dual-salesianas-ntra-sra-pilar-e1764601385552.jpg?fit=1200%2C1133&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/posts\/3598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/comments?post=3598"}],"version-history":[{"count":5,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/posts\/3598\/revisions"}],"predecessor-version":[{"id":3627,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/posts\/3598\/revisions\/3627"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/media\/3599"}],"wp:attachment":[{"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/media?parent=3598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/categories?post=3598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/tags?post=3598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}