{"id":4515,"date":"2026-06-24T07:09:16","date_gmt":"2026-06-24T07:09:16","guid":{"rendered":"https:\/\/www.academica.school\/news\/?p=4515"},"modified":"2026-06-24T07:09:16","modified_gmt":"2026-06-24T07:09:16","slug":"colegio-divino-maestro-santiago-apuesta-diploma-dual","status":"publish","type":"post","link":"https:\/\/www.academica.school\/news\/colegio-divino-maestro-santiago-apuesta-diploma-dual\/","title":{"rendered":"El Colegio Divino Maestro de Santiago de Compostela apuesta por el Diploma Dual"},"content":{"rendered":"<p>El <span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"https:\/\/www.divinomaestrosantiago.com\"><span style=\"text-decoration: underline;\"><strong>Colegio Divino Maestro de Santiago de Compostela<\/strong><\/span><\/a><\/span>\u00a0ya forma parte de los m\u00e1s de 1.000 colegios adheridos al programa Diploma Dual en Espa\u00f1a y Portugal.<\/p>\n<p><!--more--><\/p>\n<p>De esta forma, el colegio ofrece a sus alumnos la posibilidad de obtener dos titulaciones de forma simult\u00e1nea: la propia de su pa\u00eds y el American High School Diploma.<\/p>\n<div class=\"\">\n<div class=\"\">\n<div class=\"\">\n<div class=\"elementor-widget-container\">\n<p>El <a href=\"https:\/\/www.academica.school\"><strong>Diploma Dual<\/strong><\/a> es el programa oficial de convalidaci\u00f3n internacional de t\u00edtulos de Bachillerato creado y desarrollado por Academica, que permite a los alumnos obtener dos titulaciones simult\u00e1neas: la propia de su pa\u00eds y el American High School Diploma.<\/p>\n<p>Los alumnos del Diploma Dual solamente tienen que cursar 6 asignaturas para obtener la titulaci\u00f3n americana. Los convenios internacionales alcanzados por Academica y la excelencia educativa del programa permiten obtener la m\u00e1xima convalidaci\u00f3n posible: 75% de los 24 cr\u00e9ditos necesarios para obtener el American High School Diploma.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El Colegio Divino Maestro de Santiago de Compostela\u00a0ya forma parte de los m\u00e1s de 1.000 colegios adheridos al programa Diploma Dual en Espa\u00f1a y Portugal.<\/p>\n","protected":false},"author":6,"featured_media":4516,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[9,139,89,198,63,208,732,4,222,431],"class_list":["post-4515","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-last-news","tag-academica","tag-academica-spain","tag-alumnos","tag-american-high-school","tag-bachillerato-americano","tag-colegio","tag-colegio-divino-maestro","tag-diploma-dual","tag-dual-diploma","tag-los-300-mejores","clearfix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Colegio Divino Maestro de Santiago de Compostela apuesta por el Diploma Dual - Academica News<\/title>\n<meta name=\"description\" content=\"El Colegio Divino Maestro de Santiago de Compostela\u00a0ya forma parte de los m\u00e1s de 1.000 colegios adheridos al programa Diploma Dual.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.academica.school\/news\/colegio-divino-maestro-santiago-apuesta-diploma-dual\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Colegio Divino Maestro de Santiago de Compostela apuesta por el Diploma Dual - Academica News\" \/>\n<meta property=\"og:description\" content=\"El Colegio Divino Maestro de Santiago de Compostela\u00a0ya forma parte de los m\u00e1s de 1.000 colegios adheridos al programa Diploma Dual.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.academica.school\/news\/colegio-divino-maestro-santiago-apuesta-diploma-dual\/\" \/>\n<meta property=\"og:site_name\" content=\"Academica News\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-24T07:09:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.academica.school\/news\/wp-content\/uploads\/2026\/06\/diploma-dual-divino-maestro-santiago.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Academica Spain\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Academica Spain\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/colegio-divino-maestro-santiago-apuesta-diploma-dual\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/colegio-divino-maestro-santiago-apuesta-diploma-dual\\\/\"},\"author\":{\"name\":\"Academica Spain\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#\\\/schema\\\/person\\\/a9da1d35195720e471d7993db5fa06cd\"},\"headline\":\"El Colegio Divino Maestro de Santiago de Compostela apuesta por el Diploma Dual\",\"datePublished\":\"2026-06-24T07:09:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/colegio-divino-maestro-santiago-apuesta-diploma-dual\\\/\"},\"wordCount\":162,\"publisher\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/colegio-divino-maestro-santiago-apuesta-diploma-dual\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/diploma-dual-divino-maestro-santiago.jpeg?fit=1200%2C1600&ssl=1\",\"keywords\":[\"academica\",\"academica spain\",\"alumnos\",\"american high school\",\"bachillerato americano\",\"colegio\",\"colegio divino maestro\",\"Diploma Dual\",\"dual diploma\",\"los 300 mejores\"],\"articleSection\":[\"Last News\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/colegio-divino-maestro-santiago-apuesta-diploma-dual\\\/\",\"url\":\"https:\\\/\\\/www.academica.school\\\/news\\\/colegio-divino-maestro-santiago-apuesta-diploma-dual\\\/\",\"name\":\"El Colegio Divino Maestro de Santiago de Compostela apuesta por el Diploma Dual - Academica News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/colegio-divino-maestro-santiago-apuesta-diploma-dual\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/colegio-divino-maestro-santiago-apuesta-diploma-dual\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/diploma-dual-divino-maestro-santiago.jpeg?fit=1200%2C1600&ssl=1\",\"datePublished\":\"2026-06-24T07:09:16+00:00\",\"description\":\"El Colegio Divino Maestro de Santiago de Compostela\u00a0ya forma parte de los m\u00e1s de 1.000 colegios adheridos al programa Diploma Dual.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/colegio-divino-maestro-santiago-apuesta-diploma-dual\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.academica.school\\\/news\\\/colegio-divino-maestro-santiago-apuesta-diploma-dual\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/colegio-divino-maestro-santiago-apuesta-diploma-dual\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/diploma-dual-divino-maestro-santiago.jpeg?fit=1200%2C1600&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/diploma-dual-divino-maestro-santiago.jpeg?fit=1200%2C1600&ssl=1\",\"width\":1200,\"height\":1600,\"caption\":\"Visita Colegio Divino Maestro Santiago de Compostela\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/colegio-divino-maestro-santiago-apuesta-diploma-dual\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.academica.school\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Colegio Divino Maestro de Santiago de Compostela apuesta por el Diploma Dual\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/www.academica.school\\\/news\\\/\",\"name\":\"Academica News\",\"description\":\"todo lo que pasa en el mundo acad\u00e9mico, sobre universidades y cualquier evento o novedad en la que participemos\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.academica.school\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#organization\",\"name\":\"Academica\",\"url\":\"https:\\\/\\\/www.academica.school\\\/news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Captura-de-pantalla-2019-11-20-a-las-12.14.04.png?fit=799%2C500&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Captura-de-pantalla-2019-11-20-a-las-12.14.04.png?fit=799%2C500&ssl=1\",\"width\":799,\"height\":500,\"caption\":\"Academica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#\\\/schema\\\/person\\\/a9da1d35195720e471d7993db5fa06cd\",\"name\":\"Academica Spain\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7ed0e6b5e69a0c89f30117b1b70787c4c8d25c0438514a94ac82dee11b08589?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7ed0e6b5e69a0c89f30117b1b70787c4c8d25c0438514a94ac82dee11b08589?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7ed0e6b5e69a0c89f30117b1b70787c4c8d25c0438514a94ac82dee11b08589?s=96&d=mm&r=g\",\"caption\":\"Academica Spain\"},\"url\":\"https:\\\/\\\/www.academica.school\\\/news\\\/author\\\/pquecedoacademica-school\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Colegio Divino Maestro de Santiago de Compostela apuesta por el Diploma Dual - Academica News","description":"El Colegio Divino Maestro de Santiago de Compostela\u00a0ya forma parte de los m\u00e1s de 1.000 colegios adheridos al programa Diploma Dual.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.academica.school\/news\/colegio-divino-maestro-santiago-apuesta-diploma-dual\/","og_locale":"es_ES","og_type":"article","og_title":"El Colegio Divino Maestro de Santiago de Compostela apuesta por el Diploma Dual - Academica News","og_description":"El Colegio Divino Maestro de Santiago de Compostela\u00a0ya forma parte de los m\u00e1s de 1.000 colegios adheridos al programa Diploma Dual.","og_url":"https:\/\/www.academica.school\/news\/colegio-divino-maestro-santiago-apuesta-diploma-dual\/","og_site_name":"Academica News","article_published_time":"2026-06-24T07:09:16+00:00","og_image":[{"width":1200,"height":1600,"url":"https:\/\/www.academica.school\/news\/wp-content\/uploads\/2026\/06\/diploma-dual-divino-maestro-santiago.jpeg","type":"image\/jpeg"}],"author":"Academica Spain","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Academica Spain","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.academica.school\/news\/colegio-divino-maestro-santiago-apuesta-diploma-dual\/#article","isPartOf":{"@id":"https:\/\/www.academica.school\/news\/colegio-divino-maestro-santiago-apuesta-diploma-dual\/"},"author":{"name":"Academica Spain","@id":"https:\/\/www.academica.school\/news\/#\/schema\/person\/a9da1d35195720e471d7993db5fa06cd"},"headline":"El Colegio Divino Maestro de Santiago de Compostela apuesta por el Diploma Dual","datePublished":"2026-06-24T07:09:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.academica.school\/news\/colegio-divino-maestro-santiago-apuesta-diploma-dual\/"},"wordCount":162,"publisher":{"@id":"https:\/\/www.academica.school\/news\/#organization"},"image":{"@id":"https:\/\/www.academica.school\/news\/colegio-divino-maestro-santiago-apuesta-diploma-dual\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/06\/diploma-dual-divino-maestro-santiago.jpeg?fit=1200%2C1600&ssl=1","keywords":["academica","academica spain","alumnos","american high school","bachillerato americano","colegio","colegio divino maestro","Diploma Dual","dual diploma","los 300 mejores"],"articleSection":["Last News"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.academica.school\/news\/colegio-divino-maestro-santiago-apuesta-diploma-dual\/","url":"https:\/\/www.academica.school\/news\/colegio-divino-maestro-santiago-apuesta-diploma-dual\/","name":"El Colegio Divino Maestro de Santiago de Compostela apuesta por el Diploma Dual - Academica News","isPartOf":{"@id":"https:\/\/www.academica.school\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.academica.school\/news\/colegio-divino-maestro-santiago-apuesta-diploma-dual\/#primaryimage"},"image":{"@id":"https:\/\/www.academica.school\/news\/colegio-divino-maestro-santiago-apuesta-diploma-dual\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/06\/diploma-dual-divino-maestro-santiago.jpeg?fit=1200%2C1600&ssl=1","datePublished":"2026-06-24T07:09:16+00:00","description":"El Colegio Divino Maestro de Santiago de Compostela\u00a0ya forma parte de los m\u00e1s de 1.000 colegios adheridos al programa Diploma Dual.","breadcrumb":{"@id":"https:\/\/www.academica.school\/news\/colegio-divino-maestro-santiago-apuesta-diploma-dual\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.academica.school\/news\/colegio-divino-maestro-santiago-apuesta-diploma-dual\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.academica.school\/news\/colegio-divino-maestro-santiago-apuesta-diploma-dual\/#primaryimage","url":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/06\/diploma-dual-divino-maestro-santiago.jpeg?fit=1200%2C1600&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/06\/diploma-dual-divino-maestro-santiago.jpeg?fit=1200%2C1600&ssl=1","width":1200,"height":1600,"caption":"Visita Colegio Divino Maestro Santiago de Compostela"},{"@type":"BreadcrumbList","@id":"https:\/\/www.academica.school\/news\/colegio-divino-maestro-santiago-apuesta-diploma-dual\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.academica.school\/news\/"},{"@type":"ListItem","position":2,"name":"El Colegio Divino Maestro de Santiago de Compostela apuesta por el Diploma Dual"}]},{"@type":"WebSite","@id":"https:\/\/www.academica.school\/news\/#website","url":"https:\/\/www.academica.school\/news\/","name":"Academica News","description":"todo lo que pasa en el mundo acad\u00e9mico, sobre universidades y cualquier evento o novedad en la que participemos","publisher":{"@id":"https:\/\/www.academica.school\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.academica.school\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.academica.school\/news\/#organization","name":"Academica","url":"https:\/\/www.academica.school\/news\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.academica.school\/news\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2019\/11\/Captura-de-pantalla-2019-11-20-a-las-12.14.04.png?fit=799%2C500&ssl=1","contentUrl":"https:\/\/i1.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2019\/11\/Captura-de-pantalla-2019-11-20-a-las-12.14.04.png?fit=799%2C500&ssl=1","width":799,"height":500,"caption":"Academica"},"image":{"@id":"https:\/\/www.academica.school\/news\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.academica.school\/news\/#\/schema\/person\/a9da1d35195720e471d7993db5fa06cd","name":"Academica Spain","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a7ed0e6b5e69a0c89f30117b1b70787c4c8d25c0438514a94ac82dee11b08589?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a7ed0e6b5e69a0c89f30117b1b70787c4c8d25c0438514a94ac82dee11b08589?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a7ed0e6b5e69a0c89f30117b1b70787c4c8d25c0438514a94ac82dee11b08589?s=96&d=mm&r=g","caption":"Academica Spain"},"url":"https:\/\/www.academica.school\/news\/author\/pquecedoacademica-school\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/06\/diploma-dual-divino-maestro-santiago.jpeg?fit=1200%2C1600&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8RDKh-1aP","jetpack-related-posts":[{"id":3181,"url":"https:\/\/www.academica.school\/news\/colegio-divino-maestro-logrono-diploma-dual\/","url_meta":{"origin":4515,"position":0},"title":"El Colegio Divino Maestro de Logro\u00f1o apuesta por el Diploma Dual","author":"Academica Spain","date":"abril 29, 2025","format":false,"excerpt":"El Colegio Divino Maestro de Logro\u00f1o ya forma parte de los m\u00e1s de 1.000 colegios adheridos al programa Diploma Dual en Espa\u00f1a y Portugal. De esta forma, el colegio ofrece a sus alumnos la posibilidad de obtener dos titulaciones de forma simult\u00e1nea: la propia de su pa\u00eds y el American\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"diploma-dual-divino-maestro-logro\u00f1o","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/04\/diploma-dual-divino-maestro-logrono-e1745933392977.jpg?fit=600%2C659&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/04\/diploma-dual-divino-maestro-logrono-e1745933392977.jpg?fit=600%2C659&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/04\/diploma-dual-divino-maestro-logrono-e1745933392977.jpg?fit=600%2C659&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":2975,"url":"https:\/\/www.academica.school\/news\/el-colegio-compania-de-maria-de-santiago-de-compostela-amplia-su-propuesta-educativa-apostando-por-el-diploma-dual\/","url_meta":{"origin":4515,"position":1},"title":"El Colegio Compa\u00f1\u00eda de Mar\u00eda de Santiago de Compostela ampl\u00eda su propuesta educativa apostando por el Diploma Dual","author":"Academica Spain","date":"febrero 20, 2025","format":false,"excerpt":"El Colegio Compa\u00f1\u00eda de Mar\u00eda de Santiago de Compostela ya forma parte de los m\u00e1s de 1.000 colegios adheridos al programa Diploma Dual en Espa\u00f1a y Portugal. De esta forma, el colegio ofrece a sus alumnos la posibilidad de obtener dos titulaciones de forma simult\u00e1nea: la propia de su pa\u00eds\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"diploma-dual-academica","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/02\/diploma-dual-academica-7-e1740061330568.jpg?fit=600%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/02\/diploma-dual-academica-7-e1740061330568.jpg?fit=600%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/02\/diploma-dual-academica-7-e1740061330568.jpg?fit=600%2C800&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":4003,"url":"https:\/\/www.academica.school\/news\/diploma-dual-colegio-divino-maestro-logrono\/","url_meta":{"origin":4515,"position":2},"title":"El Diploma Dual en el Colegio Divino Maestro de Logro\u00f1o","author":"Academica Spain","date":"enero 29, 2026","format":"video","excerpt":"Dos alumnos que est\u00e1n cursando el Diploma Dual en el Colegio Divino Maestro de Logro\u00f1o nos cuentan su experiencia. En este v\u00eddeo nos explican en qu\u00e9 consiste el programa, adem\u00e1s de contarnos las asignaturas que est\u00e1n cursando y compartir con nosotros lo que le est\u00e1 aportando. Ambos est\u00e1n teniendo una\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3327,"url":"https:\/\/www.academica.school\/news\/colegio-torreanaz-cantabria-apuesta-por-diploma-dual\/","url_meta":{"origin":4515,"position":3},"title":"El Colegio Torre\u00e1naz de Cantabria apuesta por el Diploma Dual","author":"Academica Spain","date":"junio 20, 2025","format":false,"excerpt":"El Colegio Torre\u00e1naz de Cantabria\u00a0ya forma parte de los m\u00e1s de 1.000 colegios adheridos al programa Diploma Dual en Espa\u00f1a y Portugal. De esta forma, el colegio ofrece a sus alumnos la posibilidad de obtener dos titulaciones de forma simult\u00e1nea: la propia de su pa\u00eds y el American High School\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"diploma-dual-torreanaz","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/06\/diploma-dual-torreanaz-e1750406479695.jpg?fit=700%2C837&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/06\/diploma-dual-torreanaz-e1750406479695.jpg?fit=700%2C837&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/06\/diploma-dual-torreanaz-e1750406479695.jpg?fit=700%2C837&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/06\/diploma-dual-torreanaz-e1750406479695.jpg?fit=700%2C837&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":3296,"url":"https:\/\/www.academica.school\/news\/colegio-marista-valladolid-apuesta-bachillerato-americano\/","url_meta":{"origin":4515,"position":4},"title":"El Colegio Marista CCV de Valladolid apuesta por el Bachillerato Americano","author":"Academica Spain","date":"julio 14, 2025","format":false,"excerpt":"El Colegio Marista CCV de Valladolid\u00a0ya forma parte de los m\u00e1s de 1.000 colegios adheridos al programa Diploma Dual en Espa\u00f1a y Portugal. De esta forma, el colegio ofrece a sus alumnos la posibilidad de obtener dos titulaciones de forma simult\u00e1nea: la propia de su pa\u00eds y el American High\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"diploma-dual-maristas-ccv","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/06\/diploma-dual-maristas-ccv.jpg?fit=1000%2C750&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/06\/diploma-dual-maristas-ccv.jpg?fit=1000%2C750&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/06\/diploma-dual-maristas-ccv.jpg?fit=1000%2C750&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/06\/diploma-dual-maristas-ccv.jpg?fit=1000%2C750&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":4423,"url":"https:\/\/www.academica.school\/news\/fedac-angles-apuesta-bachillerato-dual\/","url_meta":{"origin":4515,"position":5},"title":"El Colegio FEDAC Angl\u00e8s apuesta por el Bachillerato Dual","author":"Academica Spain","date":"mayo 14, 2026","format":false,"excerpt":"El Colegio FEDAC Angl\u00e8s de Girona ya forma parte de los m\u00e1s de 1.000 colegios adheridos al programa Diploma Dual en Espa\u00f1a y Portugal. De esta forma, el colegio ofrece a sus alumnos la posibilidad de obtener dos titulaciones de forma simult\u00e1nea: la propia de su pa\u00eds y el American\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"Colegio Fedac Angles Barcelona","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/05\/diploma-dual-fedac-angles-e1778775960547.jpeg?fit=1134%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/05\/diploma-dual-fedac-angles-e1778775960547.jpeg?fit=1134%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/05\/diploma-dual-fedac-angles-e1778775960547.jpeg?fit=1134%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/05\/diploma-dual-fedac-angles-e1778775960547.jpeg?fit=1134%2C1200&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/05\/diploma-dual-fedac-angles-e1778775960547.jpeg?fit=1134%2C1200&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/posts\/4515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/comments?post=4515"}],"version-history":[{"count":1,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/posts\/4515\/revisions"}],"predecessor-version":[{"id":4517,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/posts\/4515\/revisions\/4517"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/media\/4516"}],"wp:attachment":[{"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/media?parent=4515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/categories?post=4515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/tags?post=4515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}