{"id":4518,"date":"2026-06-25T07:15:02","date_gmt":"2026-06-25T07:15:02","guid":{"rendered":"https:\/\/www.academica.school\/news\/?p=4518"},"modified":"2026-06-25T07:15:02","modified_gmt":"2026-06-25T07:15:02","slug":"asi-viven-diploma-dual-estudiantes-collegi-maristes-champagnat-badalona","status":"publish","type":"post","link":"https:\/\/www.academica.school\/news\/asi-viven-diploma-dual-estudiantes-collegi-maristes-champagnat-badalona\/","title":{"rendered":"As\u00ed viven el Diploma Dual los estudiantes del Col\u00b7legi Maristes Champagnat de Badalona"},"content":{"rendered":"<p>Los estudiantes del <span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"https:\/\/www.badalona.maristes.cat\/ca\"><span style=\"text-decoration: underline;\"><strong>Col\u00b7legi Maristes Champagnat de Badalona<\/strong><\/span><\/a><\/span> que actualmente cursan el Diploma Dual han querido compartir c\u00f3mo esta experiencia est\u00e1 contribuyendo a su desarrollo acad\u00e9mico y personal.<\/p>\n<p><!--more--><\/p>\n<div class=\"\" data-turn-id-container=\"b7afc842-c639-464c-9578-fd917926f7b2\" data-is-intersecting=\"true\">\n<p class=\"isSelectedEnd\">A lo largo del v\u00eddeo, los alumnos destacan algunas de las competencias que est\u00e1n adquiriendo gracias al programa, como la capacidad de organizar mejor su tiempo, asumir mayores responsabilidades y trabajar de forma m\u00e1s aut\u00f3noma e independiente. Adem\u00e1s, se\u00f1alan que el Diploma Dual les permite mejorar su nivel de ingl\u00e9s de una manera pr\u00e1ctica y diferente, integr\u00e1ndolo en su d\u00eda a d\u00eda.<\/p>\n<\/div>\n<p><a href=\"https:\/\/www.instagram.com\/reel\/DZUc-tEtsFQ\/?utm_source=ig_web_copy_link&amp;igsh=MzRlODBiNWFlZA==\" data-cmp-ab=\"2\"><strong><span style=\"text-decoration: underline; color: #000000;\">Enlace<\/span><\/strong><\/a> al v\u00eddeo del colegio. \u00a1Estate al tanto de todas sus noticias!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los estudiantes del Col\u00b7legi Maristes Champagnat de Badalona que actualmente cursan el Diploma Dual han querido compartir c\u00f3mo esta experiencia est\u00e1 contribuyendo a su desarrollo acad\u00e9mico y personal.<\/p>\n","protected":false},"author":6,"featured_media":4519,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[9,139,89,198,63,208,941,4,222,431],"class_list":["post-4518","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-last-news","tag-academica","tag-academica-spain","tag-alumnos","tag-american-high-school","tag-bachillerato-americano","tag-colegio","tag-colegio-maristes-champagnat","tag-diploma-dual","tag-dual-diploma","tag-los-300-mejores","clearfix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>As\u00ed viven el Diploma Dual los estudiantes del Col\u00b7legi Maristes Champagnat de Badalona - Academica News<\/title>\n<meta name=\"description\" content=\"Los estudiantes del Col\u00b7legi Maristes Champagnat de Badalona que actualmente cursan el Diploma Dual han querido compartir c\u00f3mo esta experiencia est\u00e1 contribuyendo a su desarrollo acad\u00e9mico y personal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.academica.school\/news\/asi-viven-diploma-dual-estudiantes-collegi-maristes-champagnat-badalona\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"As\u00ed viven el Diploma Dual los estudiantes del Col\u00b7legi Maristes Champagnat de Badalona - Academica News\" \/>\n<meta property=\"og:description\" content=\"Los estudiantes del Col\u00b7legi Maristes Champagnat de Badalona que actualmente cursan el Diploma Dual han querido compartir c\u00f3mo esta experiencia est\u00e1 contribuyendo a su desarrollo acad\u00e9mico y personal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.academica.school\/news\/asi-viven-diploma-dual-estudiantes-collegi-maristes-champagnat-badalona\/\" \/>\n<meta property=\"og:site_name\" content=\"Academica News\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-25T07:15:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.academica.school\/news\/wp-content\/uploads\/2026\/06\/diploma-dual-maristes-badalona-e1781696833727.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"783\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Academica Spain\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Academica Spain\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/asi-viven-diploma-dual-estudiantes-collegi-maristes-champagnat-badalona\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/asi-viven-diploma-dual-estudiantes-collegi-maristes-champagnat-badalona\\\/\"},\"author\":{\"name\":\"Academica Spain\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#\\\/schema\\\/person\\\/a9da1d35195720e471d7993db5fa06cd\"},\"headline\":\"As\u00ed viven el Diploma Dual los estudiantes del Col\u00b7legi Maristes Champagnat de Badalona\",\"datePublished\":\"2026-06-25T07:15:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/asi-viven-diploma-dual-estudiantes-collegi-maristes-champagnat-badalona\\\/\"},\"wordCount\":131,\"publisher\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/asi-viven-diploma-dual-estudiantes-collegi-maristes-champagnat-badalona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/diploma-dual-maristes-badalona-e1781696833727.png?fit=500%2C783&ssl=1\",\"keywords\":[\"academica\",\"academica spain\",\"alumnos\",\"american high school\",\"bachillerato americano\",\"colegio\",\"colegio maristes champagnat\",\"Diploma Dual\",\"dual diploma\",\"los 300 mejores\"],\"articleSection\":[\"Last News\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/asi-viven-diploma-dual-estudiantes-collegi-maristes-champagnat-badalona\\\/\",\"url\":\"https:\\\/\\\/www.academica.school\\\/news\\\/asi-viven-diploma-dual-estudiantes-collegi-maristes-champagnat-badalona\\\/\",\"name\":\"As\u00ed viven el Diploma Dual los estudiantes del Col\u00b7legi Maristes Champagnat de Badalona - Academica News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/asi-viven-diploma-dual-estudiantes-collegi-maristes-champagnat-badalona\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/asi-viven-diploma-dual-estudiantes-collegi-maristes-champagnat-badalona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/diploma-dual-maristes-badalona-e1781696833727.png?fit=500%2C783&ssl=1\",\"datePublished\":\"2026-06-25T07:15:02+00:00\",\"description\":\"Los estudiantes del Col\u00b7legi Maristes Champagnat de Badalona que actualmente cursan el Diploma Dual han querido compartir c\u00f3mo esta experiencia est\u00e1 contribuyendo a su desarrollo acad\u00e9mico y personal.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/asi-viven-diploma-dual-estudiantes-collegi-maristes-champagnat-badalona\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.academica.school\\\/news\\\/asi-viven-diploma-dual-estudiantes-collegi-maristes-champagnat-badalona\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/asi-viven-diploma-dual-estudiantes-collegi-maristes-champagnat-badalona\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/diploma-dual-maristes-badalona-e1781696833727.png?fit=500%2C783&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/diploma-dual-maristes-badalona-e1781696833727.png?fit=500%2C783&ssl=1\",\"width\":500,\"height\":783,\"caption\":\"V\u00eddeo Col\u00b7legi Maristes Champagnat Badalona\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/asi-viven-diploma-dual-estudiantes-collegi-maristes-champagnat-badalona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.academica.school\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"As\u00ed viven el Diploma Dual los estudiantes del Col\u00b7legi Maristes Champagnat de Badalona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/www.academica.school\\\/news\\\/\",\"name\":\"Academica News\",\"description\":\"todo lo que pasa en el mundo acad\u00e9mico, sobre universidades y cualquier evento o novedad en la que participemos\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.academica.school\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#organization\",\"name\":\"Academica\",\"url\":\"https:\\\/\\\/www.academica.school\\\/news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Captura-de-pantalla-2019-11-20-a-las-12.14.04.png?fit=799%2C500&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Captura-de-pantalla-2019-11-20-a-las-12.14.04.png?fit=799%2C500&ssl=1\",\"width\":799,\"height\":500,\"caption\":\"Academica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#\\\/schema\\\/person\\\/a9da1d35195720e471d7993db5fa06cd\",\"name\":\"Academica Spain\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7ed0e6b5e69a0c89f30117b1b70787c4c8d25c0438514a94ac82dee11b08589?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7ed0e6b5e69a0c89f30117b1b70787c4c8d25c0438514a94ac82dee11b08589?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7ed0e6b5e69a0c89f30117b1b70787c4c8d25c0438514a94ac82dee11b08589?s=96&d=mm&r=g\",\"caption\":\"Academica Spain\"},\"url\":\"https:\\\/\\\/www.academica.school\\\/news\\\/author\\\/pquecedoacademica-school\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"As\u00ed viven el Diploma Dual los estudiantes del Col\u00b7legi Maristes Champagnat de Badalona - Academica News","description":"Los estudiantes del Col\u00b7legi Maristes Champagnat de Badalona que actualmente cursan el Diploma Dual han querido compartir c\u00f3mo esta experiencia est\u00e1 contribuyendo a su desarrollo acad\u00e9mico y personal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.academica.school\/news\/asi-viven-diploma-dual-estudiantes-collegi-maristes-champagnat-badalona\/","og_locale":"es_ES","og_type":"article","og_title":"As\u00ed viven el Diploma Dual los estudiantes del Col\u00b7legi Maristes Champagnat de Badalona - Academica News","og_description":"Los estudiantes del Col\u00b7legi Maristes Champagnat de Badalona que actualmente cursan el Diploma Dual han querido compartir c\u00f3mo esta experiencia est\u00e1 contribuyendo a su desarrollo acad\u00e9mico y personal.","og_url":"https:\/\/www.academica.school\/news\/asi-viven-diploma-dual-estudiantes-collegi-maristes-champagnat-badalona\/","og_site_name":"Academica News","article_published_time":"2026-06-25T07:15:02+00:00","og_image":[{"width":500,"height":783,"url":"https:\/\/www.academica.school\/news\/wp-content\/uploads\/2026\/06\/diploma-dual-maristes-badalona-e1781696833727.png","type":"image\/png"}],"author":"Academica Spain","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Academica Spain","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.academica.school\/news\/asi-viven-diploma-dual-estudiantes-collegi-maristes-champagnat-badalona\/#article","isPartOf":{"@id":"https:\/\/www.academica.school\/news\/asi-viven-diploma-dual-estudiantes-collegi-maristes-champagnat-badalona\/"},"author":{"name":"Academica Spain","@id":"https:\/\/www.academica.school\/news\/#\/schema\/person\/a9da1d35195720e471d7993db5fa06cd"},"headline":"As\u00ed viven el Diploma Dual los estudiantes del Col\u00b7legi Maristes Champagnat de Badalona","datePublished":"2026-06-25T07:15:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.academica.school\/news\/asi-viven-diploma-dual-estudiantes-collegi-maristes-champagnat-badalona\/"},"wordCount":131,"publisher":{"@id":"https:\/\/www.academica.school\/news\/#organization"},"image":{"@id":"https:\/\/www.academica.school\/news\/asi-viven-diploma-dual-estudiantes-collegi-maristes-champagnat-badalona\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/06\/diploma-dual-maristes-badalona-e1781696833727.png?fit=500%2C783&ssl=1","keywords":["academica","academica spain","alumnos","american high school","bachillerato americano","colegio","colegio maristes champagnat","Diploma Dual","dual diploma","los 300 mejores"],"articleSection":["Last News"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.academica.school\/news\/asi-viven-diploma-dual-estudiantes-collegi-maristes-champagnat-badalona\/","url":"https:\/\/www.academica.school\/news\/asi-viven-diploma-dual-estudiantes-collegi-maristes-champagnat-badalona\/","name":"As\u00ed viven el Diploma Dual los estudiantes del Col\u00b7legi Maristes Champagnat de Badalona - Academica News","isPartOf":{"@id":"https:\/\/www.academica.school\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.academica.school\/news\/asi-viven-diploma-dual-estudiantes-collegi-maristes-champagnat-badalona\/#primaryimage"},"image":{"@id":"https:\/\/www.academica.school\/news\/asi-viven-diploma-dual-estudiantes-collegi-maristes-champagnat-badalona\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/06\/diploma-dual-maristes-badalona-e1781696833727.png?fit=500%2C783&ssl=1","datePublished":"2026-06-25T07:15:02+00:00","description":"Los estudiantes del Col\u00b7legi Maristes Champagnat de Badalona que actualmente cursan el Diploma Dual han querido compartir c\u00f3mo esta experiencia est\u00e1 contribuyendo a su desarrollo acad\u00e9mico y personal.","breadcrumb":{"@id":"https:\/\/www.academica.school\/news\/asi-viven-diploma-dual-estudiantes-collegi-maristes-champagnat-badalona\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.academica.school\/news\/asi-viven-diploma-dual-estudiantes-collegi-maristes-champagnat-badalona\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.academica.school\/news\/asi-viven-diploma-dual-estudiantes-collegi-maristes-champagnat-badalona\/#primaryimage","url":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/06\/diploma-dual-maristes-badalona-e1781696833727.png?fit=500%2C783&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/06\/diploma-dual-maristes-badalona-e1781696833727.png?fit=500%2C783&ssl=1","width":500,"height":783,"caption":"V\u00eddeo Col\u00b7legi Maristes Champagnat Badalona"},{"@type":"BreadcrumbList","@id":"https:\/\/www.academica.school\/news\/asi-viven-diploma-dual-estudiantes-collegi-maristes-champagnat-badalona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.academica.school\/news\/"},{"@type":"ListItem","position":2,"name":"As\u00ed viven el Diploma Dual los estudiantes del Col\u00b7legi Maristes Champagnat de Badalona"}]},{"@type":"WebSite","@id":"https:\/\/www.academica.school\/news\/#website","url":"https:\/\/www.academica.school\/news\/","name":"Academica News","description":"todo lo que pasa en el mundo acad\u00e9mico, sobre universidades y cualquier evento o novedad en la que participemos","publisher":{"@id":"https:\/\/www.academica.school\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.academica.school\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.academica.school\/news\/#organization","name":"Academica","url":"https:\/\/www.academica.school\/news\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.academica.school\/news\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2019\/11\/Captura-de-pantalla-2019-11-20-a-las-12.14.04.png?fit=799%2C500&ssl=1","contentUrl":"https:\/\/i1.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2019\/11\/Captura-de-pantalla-2019-11-20-a-las-12.14.04.png?fit=799%2C500&ssl=1","width":799,"height":500,"caption":"Academica"},"image":{"@id":"https:\/\/www.academica.school\/news\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.academica.school\/news\/#\/schema\/person\/a9da1d35195720e471d7993db5fa06cd","name":"Academica Spain","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a7ed0e6b5e69a0c89f30117b1b70787c4c8d25c0438514a94ac82dee11b08589?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a7ed0e6b5e69a0c89f30117b1b70787c4c8d25c0438514a94ac82dee11b08589?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a7ed0e6b5e69a0c89f30117b1b70787c4c8d25c0438514a94ac82dee11b08589?s=96&d=mm&r=g","caption":"Academica Spain"},"url":"https:\/\/www.academica.school\/news\/author\/pquecedoacademica-school\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/06\/diploma-dual-maristes-badalona-e1781696833727.png?fit=500%2C783&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8RDKh-1aS","jetpack-related-posts":[{"id":3457,"url":"https:\/\/www.academica.school\/news\/visita-collegi-sant-andreu-badalona\/","url_meta":{"origin":4518,"position":0},"title":"Visita al Col\u00b7legi Sant Andreu de Badalona","author":"Academica Spain","date":"octubre 10, 2025","format":false,"excerpt":"Nos ha encantado visitar el Col\u00b7legi Sant Andreu de Badalona y conocer de primera mano el progreso de los estudiantes que est\u00e1n cursando el programa Diploma Dual. El Diploma Dual es el programa oficial de convalidaci\u00f3n internacional de t\u00edtulos de Bachillerato creado y desarrollado por Academica, que permite a los\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"diploma-dual-sant-andreu","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/10\/diploma-dual-sant-andreu-e1760096023483.jpg?fit=951%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/10\/diploma-dual-sant-andreu-e1760096023483.jpg?fit=951%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/10\/diploma-dual-sant-andreu-e1760096023483.jpg?fit=951%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/10\/diploma-dual-sant-andreu-e1760096023483.jpg?fit=951%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":3477,"url":"https:\/\/www.academica.school\/news\/diploma-dual-collegi-maristes-champagnat-badalona\/","url_meta":{"origin":4518,"position":1},"title":"El Diploma Dual en el Col\u00b7legi Maristes Champagnat de Badalona","author":"Academica Spain","date":"octubre 14, 2025","format":false,"excerpt":"Hemos visitado el Col\u00b7legi Maristes Champagnat de Badalona para ver a los alumnos que est\u00e1n cursando el Diploma Dual. El Diploma Dual es el programa oficial de convalidaci\u00f3n internacional de t\u00edtulos de Bachillerato creado y desarrollado por Academica, que permite a los alumnos obtener dos titulaciones simult\u00e1neas: la propia de\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"diploma-dual-maristes-champagnat","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/10\/diploma-dual-maristes-champagnat.jpg?fit=1051%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/10\/diploma-dual-maristes-champagnat.jpg?fit=1051%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/10\/diploma-dual-maristes-champagnat.jpg?fit=1051%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/10\/diploma-dual-maristes-champagnat.jpg?fit=1051%2C1200&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/10\/diploma-dual-maristes-champagnat.jpg?fit=1051%2C1200&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":3677,"url":"https:\/\/www.academica.school\/news\/garbi-pere-verges-badalona-compromiso-acompanamiento\/","url_meta":{"origin":4518,"position":2},"title":"Colegio Garb\u00ed Pere Verg\u00e9s en Badalona: compromiso, acompa\u00f1amiento y grandes resultados en el Diploma Dual","author":"Academica Spain","date":"noviembre 4, 2025","format":false,"excerpt":"Hemos visitado el Colegio Garb\u00ed Pere Verg\u00e9s en Badalona para conocer de cerca el trabajo que el centro y sus estudiantes est\u00e1n realizando dentro del programa Diploma Dual. Durante la visita, hemos podido comprobar el excelente entorno educativo que ofrece el colegio: un espacio que fomenta el desarrollo integral de\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/11\/diploma-dual-garbi-pere-verges-e1763971801689.jpg?fit=1000%2C1120&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/11\/diploma-dual-garbi-pere-verges-e1763971801689.jpg?fit=1000%2C1120&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/11\/diploma-dual-garbi-pere-verges-e1763971801689.jpg?fit=1000%2C1120&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/11\/diploma-dual-garbi-pere-verges-e1763971801689.jpg?fit=1000%2C1120&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":3532,"url":"https:\/\/www.academica.school\/news\/conociendo-alumnos-diploma-dual-collegi-sant-gabriel\/","url_meta":{"origin":4518,"position":3},"title":"Conociendo a los alumnos del Diploma Dual del Col\u00b7legi Sant Gabriel de Barcelona","author":"Academica Spain","date":"octubre 23, 2025","format":false,"excerpt":"Hemos estado en el Col\u00b7legi Sant Gabriel de Barcelona para conocer a los alumnos que est\u00e1n cursando el Diploma Dual. El Diploma Dual es el programa oficial de convalidaci\u00f3n internacional de t\u00edtulos de Bachillerato creado y desarrollado por Academica, que permite a los alumnos obtener dos titulaciones simult\u00e1neas: la propia\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"Visita a los alumnos del Col\u00b7legi Sant Gabriel de Barcelona","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/10\/diploma-dual-sant-gabriel-2.jpg?fit=1000%2C832&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/10\/diploma-dual-sant-gabriel-2.jpg?fit=1000%2C832&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/10\/diploma-dual-sant-gabriel-2.jpg?fit=1000%2C832&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/10\/diploma-dual-sant-gabriel-2.jpg?fit=1000%2C832&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":4490,"url":"https:\/\/www.academica.school\/news\/diploma-dual-colegio-salesians-badalona\/","url_meta":{"origin":4518,"position":4},"title":"El Diploma Dual en el Colegio Salesians de Badalona","author":"Academica Spain","date":"junio 18, 2026","format":false,"excerpt":"Aral y Georgina, alumnas del Colegio Salesians de Badalona, comparten su experiencia del Diploma Dual a trav\u00e9s de este v\u00eddeo. En el v\u00eddeo, las estudiantes destacan la mejora de su nivel de ingl\u00e9s, el aprendizaje de una cultura diferente y la posibilidad de cursar asignaturas que no se ofrecen en\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"V\u00eddeo Colegio Salesians Badalona","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/06\/diploma-dual-salesians-badalona-e1780915119541.png?fit=785%2C772&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/06\/diploma-dual-salesians-badalona-e1780915119541.png?fit=785%2C772&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/06\/diploma-dual-salesians-badalona-e1780915119541.png?fit=785%2C772&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2026\/06\/diploma-dual-salesians-badalona-e1780915119541.png?fit=785%2C772&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":3429,"url":"https:\/\/www.academica.school\/news\/visita-collegi-singuerlin-barcelona\/","url_meta":{"origin":4518,"position":5},"title":"Visita al Col\u00b7legi Singuerl\u00edn de Barcelona","author":"Academica Spain","date":"octubre 9, 2025","format":false,"excerpt":"Hemos tenido el placer de visitar el Col\u00b7legi Singuerl\u00edn de Barcelona para conocer de cerca c\u00f3mo est\u00e1n avanzando los estudiantes que cursan el programa Diploma Dual. El Diploma Dual es el programa oficial de convalidaci\u00f3n internacional de t\u00edtulos de Bachillerato creado y desarrollado por Academica, que permite a los alumnos\u2026","rel":"","context":"En \u00abLast News\u00bb","block_context":{"text":"Last News","link":"https:\/\/www.academica.school\/news\/last-news\/"},"img":{"alt_text":"diploma-dual-singuerlin","src":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/10\/diploma-dual-singuerlin-scaled-e1760000310888.jpg?fit=862%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/10\/diploma-dual-singuerlin-scaled-e1760000310888.jpg?fit=862%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/10\/diploma-dual-singuerlin-scaled-e1760000310888.jpg?fit=862%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2025\/10\/diploma-dual-singuerlin-scaled-e1760000310888.jpg?fit=862%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/posts\/4518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/comments?post=4518"}],"version-history":[{"count":1,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/posts\/4518\/revisions"}],"predecessor-version":[{"id":4520,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/posts\/4518\/revisions\/4520"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/media\/4519"}],"wp:attachment":[{"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/media?parent=4518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/categories?post=4518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/tags?post=4518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}