{"id":775,"count":1,"description":"","link":"https:\/\/www.academica.school\/news\/tag\/colegio-san-jose-calasanz\/","name":"Colegio San Jos\u00e9 calasanz","slug":"colegio-san-jose-calasanz","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Colegio San Jos\u00e9 calasanz archivos - Academica News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.academica.school\/news\/tag\/colegio-san-jose-calasanz\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Colegio San Jos\u00e9 calasanz archivos - Academica News\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.academica.school\/news\/tag\/colegio-san-jose-calasanz\/\" \/>\n<meta property=\"og:site_name\" content=\"Academica News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/tag\\\/colegio-san-jose-calasanz\\\/\",\"url\":\"https:\\\/\\\/www.academica.school\\\/news\\\/tag\\\/colegio-san-jose-calasanz\\\/\",\"name\":\"Colegio San Jos\u00e9 calasanz archivos - Academica News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/tag\\\/colegio-san-jose-calasanz\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/tag\\\/colegio-san-jose-calasanz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.academica.school\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Colegio San Jos\u00e9 calasanz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/www.academica.school\\\/news\\\/\",\"name\":\"Academica News\",\"description\":\"todo lo que pasa en el mundo acad\u00e9mico, sobre universidades y cualquier evento o novedad en la que participemos\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.academica.school\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#organization\",\"name\":\"Academica\",\"url\":\"https:\\\/\\\/www.academica.school\\\/news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Captura-de-pantalla-2019-11-20-a-las-12.14.04.png?fit=799%2C500&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/www.academica.school\\\/news\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Captura-de-pantalla-2019-11-20-a-las-12.14.04.png?fit=799%2C500&ssl=1\",\"width\":799,\"height\":500,\"caption\":\"Academica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.academica.school\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Colegio San Jos\u00e9 calasanz archivos - Academica News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.academica.school\/news\/tag\/colegio-san-jose-calasanz\/","og_locale":"es_ES","og_type":"article","og_title":"Colegio San Jos\u00e9 calasanz archivos - Academica News","og_url":"https:\/\/www.academica.school\/news\/tag\/colegio-san-jose-calasanz\/","og_site_name":"Academica News","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.academica.school\/news\/tag\/colegio-san-jose-calasanz\/","url":"https:\/\/www.academica.school\/news\/tag\/colegio-san-jose-calasanz\/","name":"Colegio San Jos\u00e9 calasanz archivos - Academica News","isPartOf":{"@id":"https:\/\/www.academica.school\/news\/#website"},"breadcrumb":{"@id":"https:\/\/www.academica.school\/news\/tag\/colegio-san-jose-calasanz\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.academica.school\/news\/tag\/colegio-san-jose-calasanz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.academica.school\/news\/"},{"@type":"ListItem","position":2,"name":"Colegio San Jos\u00e9 calasanz"}]},{"@type":"WebSite","@id":"https:\/\/www.academica.school\/news\/#website","url":"https:\/\/www.academica.school\/news\/","name":"Academica News","description":"todo lo que pasa en el mundo acad\u00e9mico, sobre universidades y cualquier evento o novedad en la que participemos","publisher":{"@id":"https:\/\/www.academica.school\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.academica.school\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.academica.school\/news\/#organization","name":"Academica","url":"https:\/\/www.academica.school\/news\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.academica.school\/news\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2019\/11\/Captura-de-pantalla-2019-11-20-a-las-12.14.04.png?fit=799%2C500&ssl=1","contentUrl":"https:\/\/i1.wp.com\/www.academica.school\/news\/wp-content\/uploads\/2019\/11\/Captura-de-pantalla-2019-11-20-a-las-12.14.04.png?fit=799%2C500&ssl=1","width":799,"height":500,"caption":"Academica"},"image":{"@id":"https:\/\/www.academica.school\/news\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/tags\/775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.academica.school\/news\/wp-json\/wp\/v2\/posts?tags=775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}